{"id":13,"date":"2024-08-30T22:40:50","date_gmt":"2024-08-30T22:40:50","guid":{"rendered":"https:\/\/prime-payal-05hl1.zipwp.link\/religious-gifts\/"},"modified":"2024-08-30T22:40:50","modified_gmt":"2024-08-30T22:40:50","slug":"religious-gifts","status":"publish","type":"page","link":"https:\/\/www.blumenhandlerflorist.com\/fr\/cadeaux-religieux\/","title":{"rendered":"Cadeaux religieux"},"content":{"rendered":"<div class=\"wp-block-uagb-container uagb-block-5657136f alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-info-box uagb-block-48b77c69 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h1 class=\"uagb-ifb-title\">Page des cadeaux religieux<\/h1><\/div><p class=\"uagb-ifb-desc\">D\u00e9couvrez des compositions florales pour toutes les occasions<\/p><\/div><\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-uagb-container uagb-block-8c4383c7 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-d4a03254\">\n<div class=\"wp-block-uagb-info-box uagb-block-7edef7ac uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h6 class=\"uagb-ifb-title-prefix\">\u00c0 propos de nous<\/h6><h3 class=\"uagb-ifb-title\">Expertise en mati\u00e8re de livraison internationale de fleurs<\/h3><\/div><p class=\"uagb-ifb-desc\">Blumenhandler Florist se sp\u00e9cialise dans la livraison internationale de fleurs, en veillant \u00e0 ce que vos \u00e9motions et vos expressions soient magnifiquement transmises par nos cr\u00e9ations florales. Notre engagement pour l'excellence et la satisfaction de nos clients nous pousse \u00e0 fournir des solutions innovantes et des services exceptionnels, permettant aux individus d'atteindre la grandeur. Gr\u00e2ce \u00e0 notre \u00e9quipe d\u00e9vou\u00e9e et \u00e0 notre volont\u00e9 de faire des r\u00eaves une r\u00e9alit\u00e9, nous visons \u00e0 obtenir des r\u00e9sultats in\u00e9gal\u00e9s et \u00e0 cr\u00e9er un impact positif. Rejoignez-nous sur ce chemin de l'autonomisation et laissez-nous vous aider \u00e0 transformer vos aspirations en r\u00e9alit\u00e9.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-5b4bff5d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap\">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-de3d4e0e wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\"><div class=\"uagb-button__link\">En savoir plus<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-699445d0\">\n<div class=\"wp-block-uagb-container uagb-block-230a853e\">\n<div class=\"wp-block-uagb-image alignleft uagb-block-1bc337b7 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-01-1024x683.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-01.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-01.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-01-1024x683.jpg\" alt=\"\" class=\"uag-image-80569 lazyload\" width=\"270\" height=\"360\" title=\"\" loading=\"lazy\" role=\"img\"\/><noscript><img decoding=\"async\" srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-01-1024x683.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-01.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-01.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-01-1024x683.jpg\" alt=\"\" class=\"uag-image-80569 lazyload\" width=\"270\" height=\"360\" title=\"\" loading=\"lazy\" role=\"img\"\/><\/noscript><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-9f131a21\">\n<div class=\"wp-block-uagb-image alignleft uagb-block-7482949b wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/mountains-01-1024x683.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/mountains-01.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/mountains-01.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/mountains-01-1024x683.jpg\" alt=\"\" class=\"uag-image-80571 lazyload\" width=\"270\" height=\"360\" title=\"\" loading=\"lazy\" role=\"img\"\/><noscript><img decoding=\"async\" srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/mountains-01-1024x683.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/mountains-01.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/mountains-01.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/mountains-01-1024x683.jpg\" alt=\"\" class=\"uag-image-80571 lazyload\" width=\"270\" height=\"360\" title=\"\" loading=\"lazy\" role=\"img\"\/><\/noscript><\/figure><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-uagb-container uagb-block-323c7320 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-info-box uagb-block-9fbe867d uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h2 class=\"uagb-ifb-title\">Solutions \u00e9l\u00e9gantes de d\u00e9coration florale<\/h2><\/div><p class=\"uagb-ifb-desc\">D\u00e9couvrez notre large gamme de services floraux con\u00e7us pour rehausser vos occasions sp\u00e9ciales.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-682319ac\">\n<div class=\"wp-block-uagb-container uagb-block-71e8fff3\">\n<div class=\"wp-block-uagb-image alignleft uagb-block-75ccde33 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/natures-01-1024x683.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/natures-02.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/natures-02.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/natures-01-1024x683.jpg\" alt=\"\" class=\"uag-image-80573 lazyload\" width=\"368\" height=\"450\" title=\"\" loading=\"lazy\"\/><noscript><img decoding=\"async\" srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/natures-01-1024x683.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/natures-02.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/natures-02.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/natures-01-1024x683.jpg\" alt=\"\" class=\"uag-image-80573 lazyload\" width=\"368\" height=\"450\" title=\"\" loading=\"lazy\"\/><\/noscript><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-9ee67bb3\">\n<div class=\"wp-block-uagb-info-box uagb-block-2ab09e50 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">Location d'\u00e9v\u00e9nements<\/h4><\/div><p class=\"uagb-ifb-desc\">Parcourez notre collection exquise de locations \u00e9v\u00e9nementielles qui ajoutent une touche d'\u00e9l\u00e9gance \u00e0 vos c\u00e9l\u00e9brations.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-64373be9\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap\">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-15570a3f wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" href=\"#\" onclick=\"return false;\" rel=\"follow noopener\" target=\"_self\"><div class=\"uagb-button__link\">En savoir plus<\/div><span class=\"uagb-button__icon uagb-button__icon-position-after\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 320 512\"><path d=\"M96 480c-8.188 0-16.38-3.125-22.62-9.375c-12.5-12.5-12.5-32.75 0-45.25L242.8 256L73.38 86.63c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0l192 192c12.5 12.5 12.5 32.75 0 45.25l-192 192C112.4 476.9 104.2 480 96 480z\"><\/path><\/svg><\/span><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-a767bc2d\">\n<div class=\"wp-block-uagb-image alignleft uagb-block-b2504f0e wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-01-1024x683.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-02.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-02.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-01-1024x683.jpg\" alt=\"\" class=\"uag-image-80569 lazyload\" width=\"368\" height=\"450\" title=\"\" loading=\"lazy\"\/><noscript><img decoding=\"async\" srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-01-1024x683.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-02.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-02.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-01-1024x683.jpg\" alt=\"\" class=\"uag-image-80569 lazyload\" width=\"368\" height=\"450\" title=\"\" loading=\"lazy\"\/><\/noscript><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-9aef83d0\">\n<div class=\"wp-block-uagb-info-box uagb-block-7e10dc31 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">Conception florale<\/h4><\/div><p class=\"uagb-ifb-desc\">Plongez dans l'art de la conception florale avec nos arrangements r\u00e9alis\u00e9s par des experts qui captivent les sens.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-66047323\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap\">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-5658abd4 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" href=\"#\" onclick=\"return false;\" rel=\"follow noopener\" target=\"_self\"><div class=\"uagb-button__link\">En savoir plus<\/div><span class=\"uagb-button__icon uagb-button__icon-position-after\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 320 512\"><path d=\"M96 480c-8.188 0-16.38-3.125-22.62-9.375c-12.5-12.5-12.5-32.75 0-45.25L242.8 256L73.38 86.63c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0l192 192c12.5 12.5 12.5 32.75 0 45.25l-192 192C112.4 476.9 104.2 480 96 480z\"><\/path><\/svg><\/span><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-1add9e25\">\n<div class=\"wp-block-uagb-image alignleft uagb-block-cf6d3a59 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/rivers-01-1024x683.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/rivers-01.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/rivers-01.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/rivers-01-1024x683.jpg\" alt=\"\" class=\"uag-image-80575 lazyload\" width=\"368\" height=\"450\" title=\"\" loading=\"lazy\"\/><noscript><img decoding=\"async\" srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/rivers-01-1024x683.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/rivers-01.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/rivers-01.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/rivers-01-1024x683.jpg\" alt=\"\" class=\"uag-image-80575 lazyload\" width=\"368\" height=\"450\" title=\"\" loading=\"lazy\"\/><\/noscript><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-8e1bc111\">\n<div class=\"wp-block-uagb-info-box uagb-block-3ce36a5e uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">Cr\u00e9ations sur mesure<\/h4><\/div><p class=\"uagb-ifb-desc\">D\u00e9couvrez la magie des cr\u00e9ations florales personnalis\u00e9es, adapt\u00e9es \u00e0 vos pr\u00e9f\u00e9rences et \u00e0 vos occasions, pour des moments inoubliables.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-7e724e0b\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap\">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-a3d0307e wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" href=\"#\" onclick=\"return false;\" rel=\"follow noopener\" target=\"_self\"><div class=\"uagb-button__link\">En savoir plus<\/div><span class=\"uagb-button__icon uagb-button__icon-position-after\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 320 512\"><path d=\"M96 480c-8.188 0-16.38-3.125-22.62-9.375c-12.5-12.5-12.5-32.75 0-45.25L242.8 256L73.38 86.63c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0l192 192c12.5 12.5 12.5 32.75 0 45.25l-192 192C112.4 476.9 104.2 480 96 480z\"><\/path><\/svg><\/span><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-uagb-container uagb-block-1202b3b6 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-f854eaf6\">\n<div class=\"wp-block-uagb-info-box uagb-block-4f577d90 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h2 class=\"uagb-ifb-title\">Des services uniques de conception florale sont disponibles ici<\/h2><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-fdb34588 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><\/div><p class=\"uagb-ifb-desc\">Am\u00e9liorez votre exp\u00e9rience florale gr\u00e2ce \u00e0 notre gamme exclusive de services.<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-3c078708\">\n<div class=\"wp-block-uagb-container uagb-block-694ce816\">\n<div class=\"wp-block-uagb-info-box uagb-block-d49ddba8 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M438.6 105.4C451.1 117.9 451.1 138.1 438.6 150.6L182.6 406.6C170.1 419.1 149.9 419.1 137.4 406.6L9.372 278.6C-3.124 266.1-3.124 245.9 9.372 233.4C21.87 220.9 42.13 220.9 54.63 233.4L159.1 338.7L393.4 105.4C405.9 92.88 426.1 92.88 438.6 105.4H438.6z\"><\/path><\/svg><\/div><\/div><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">Conseil strat\u00e9gique<\/h4><\/div><p class=\"uagb-ifb-desc\">Partagez quelques d\u00e9tails ici pour le Service one. Il s'agit d'une section flexible dans laquelle vous pouvez partager tout ce que vous voulez. Il peut s'agir de d\u00e9tails ou d'informations sur votre service.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-08292118\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap\">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-4fc7d6a2 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\"><div class=\"uagb-button__link\">Lire la suite<\/div><span class=\"uagb-button__icon uagb-button__icon-position-after\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 320 512\" aria-hidden=\"true\" focussable=\"false\"><path d=\"M96 480c-8.188 0-16.38-3.125-22.62-9.375c-12.5-12.5-12.5-32.75 0-45.25L242.8 256L73.38 86.63c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0l192 192c12.5 12.5 12.5 32.75 0 45.25l-192 192C112.4 476.9 104.2 480 96 480z\"><\/path><\/svg><\/span><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-b558d6ab\">\n<div class=\"wp-block-uagb-info-box uagb-block-ab9e8375 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M438.6 105.4C451.1 117.9 451.1 138.1 438.6 150.6L182.6 406.6C170.1 419.1 149.9 419.1 137.4 406.6L9.372 278.6C-3.124 266.1-3.124 245.9 9.372 233.4C21.87 220.9 42.13 220.9 54.63 233.4L159.1 338.7L393.4 105.4C405.9 92.88 426.1 92.88 438.6 105.4H438.6z\"><\/path><\/svg><\/div><\/div><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">Marketing num\u00e9rique<\/h4><\/div><p class=\"uagb-ifb-desc\">Partagez quelques d\u00e9tails ici pour le service deux. Il s'agit d'une section flexible dans laquelle vous pouvez partager ce que vous voulez. Il peut s'agir de d\u00e9tails ou d'informations sur votre service.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-fdf46656\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap\">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-32051b39 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\"><div class=\"uagb-button__link\">Lire la suite<\/div><span class=\"uagb-button__icon uagb-button__icon-position-after\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 320 512\" aria-hidden=\"true\" focussable=\"false\"><path d=\"M96 480c-8.188 0-16.38-3.125-22.62-9.375c-12.5-12.5-12.5-32.75 0-45.25L242.8 256L73.38 86.63c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0l192 192c12.5 12.5 12.5 32.75 0 45.25l-192 192C112.4 476.9 104.2 480 96 480z\"><\/path><\/svg><\/span><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-861d4591\">\n<div class=\"wp-block-uagb-info-box uagb-block-2757b255 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M438.6 105.4C451.1 117.9 451.1 138.1 438.6 150.6L182.6 406.6C170.1 419.1 149.9 419.1 137.4 406.6L9.372 278.6C-3.124 266.1-3.124 245.9 9.372 233.4C21.87 220.9 42.13 220.9 54.63 233.4L159.1 338.7L393.4 105.4C405.9 92.88 426.1 92.88 438.6 105.4H438.6z\"><\/path><\/svg><\/div><\/div><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">Solutions technologiques<\/h4><\/div><p class=\"uagb-ifb-desc\">Partagez quelques d\u00e9tails ici pour le service trois. Il s'agit d'une section flexible dans laquelle vous pouvez partager ce que vous voulez. Il peut s'agir de d\u00e9tails ou d'informations sur votre service.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-fd943482\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap\">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-941fa188 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\"><div class=\"uagb-button__link\">Lire la suite<\/div><span class=\"uagb-button__icon uagb-button__icon-position-after\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 320 512\" aria-hidden=\"true\" focussable=\"false\"><path d=\"M96 480c-8.188 0-16.38-3.125-22.62-9.375c-12.5-12.5-12.5-32.75 0-45.25L242.8 256L73.38 86.63c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0l192 192c12.5 12.5 12.5 32.75 0 45.25l-192 192C112.4 476.9 104.2 480 96 480z\"><\/path><\/svg><\/span><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-uagb-container uagb-block-dd28d95c alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-609fec64\">\n<div class=\"wp-block-uagb-container uagb-block-72f13e20\">\n<div class=\"wp-block-uagb-info-box uagb-block-1882db2b uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h2 class=\"uagb-ifb-title\">Collection de cadeaux religieux exquis<\/h2><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-4a8d035b\">\n<div class=\"wp-block-uagb-info-box uagb-block-3a19b4ea uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><p class=\"uagb-ifb-title\">Mat\u00e9riaux de premi\u00e8re qualit\u00e9 et options personnalisables pour les c\u00e9r\u00e9monies religieuses, cr\u00e9ant des arrangements sur mesure.<\/p><\/div><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-8f6c422d\">\n<div class=\"wp-block-uagb-container uagb-block-0ba6d01d\">\n<div class=\"wp-block-uagb-image alignleft uagb-block-4e75022d wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/09\/gallery-27.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/09\/gallery-27.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/09\/gallery-27.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/09\/gallery-27.jpg\" alt=\"\" class=\"uag-image-76153 lazyload\" width=\"600\" height=\"500\" title=\"\" loading=\"lazy\" role=\"img\"\/><noscript><img decoding=\"async\" srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/09\/gallery-27.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/09\/gallery-27.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/09\/gallery-27.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/09\/gallery-27.jpg\" alt=\"\" class=\"uag-image-76153 lazyload\" width=\"600\" height=\"500\" title=\"\" loading=\"lazy\" role=\"img\"\/><\/noscript><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-56e1cd58\">\n<div class=\"wp-block-uagb-container uagb-block-f2a241b1\">\n<div class=\"wp-block-uagb-info-box uagb-block-c5554396 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M438.6 105.4C451.1 117.9 451.1 138.1 438.6 150.6L182.6 406.6C170.1 419.1 149.9 419.1 137.4 406.6L9.372 278.6C-3.124 266.1-3.124 245.9 9.372 233.4C21.87 220.9 42.13 220.9 54.63 233.4L159.1 338.7L393.4 105.4C405.9 92.88 426.1 92.88 438.6 105.4H438.6z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">Cadeaux floraux uniques<\/h4><\/div><p class=\"uagb-ifb-desc\">Pr\u00e9sentation d'une s\u00e9lection de cadeaux floraux adapt\u00e9s aux \u00e9v\u00e9nements spirituels, ajoutant beaut\u00e9 et \u00e9l\u00e9gance.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-b685501a uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M438.6 105.4C451.1 117.9 451.1 138.1 438.6 150.6L182.6 406.6C170.1 419.1 149.9 419.1 137.4 406.6L9.372 278.6C-3.124 266.1-3.124 245.9 9.372 233.4C21.87 220.9 42.13 220.9 54.63 233.4L159.1 338.7L393.4 105.4C405.9 92.88 426.1 92.88 438.6 105.4H438.6z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">Options personnalis\u00e9es<\/h4><\/div><p class=\"uagb-ifb-desc\">Personnalisez vos choix de cadeaux \u00e0 l'aide de nos outils de personnalisation faciles \u00e0 utiliser, afin de rehausser le sentiment de votre geste.<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-737a9fe3\">\n<div class=\"wp-block-uagb-info-box uagb-block-b31d2911 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M438.6 105.4C451.1 117.9 451.1 138.1 438.6 150.6L182.6 406.6C170.1 419.1 149.9 419.1 137.4 406.6L9.372 278.6C-3.124 266.1-3.124 245.9 9.372 233.4C21.87 220.9 42.13 220.9 54.63 233.4L159.1 338.7L393.4 105.4C405.9 92.88 426.1 92.88 438.6 105.4H438.6z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">Designs \u00e9l\u00e9gants<\/h4><\/div><p class=\"uagb-ifb-desc\">D\u00e9couvrez des compositions florales sophistiqu\u00e9es qui symbolisent la foi et la d\u00e9votion, r\u00e9alis\u00e9es avec le souci du d\u00e9tail.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-75008db2 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M438.6 105.4C451.1 117.9 451.1 138.1 438.6 150.6L182.6 406.6C170.1 419.1 149.9 419.1 137.4 406.6L9.372 278.6C-3.124 266.1-3.124 245.9 9.372 233.4C21.87 220.9 42.13 220.9 54.63 233.4L159.1 338.7L393.4 105.4C405.9 92.88 426.1 92.88 438.6 105.4H438.6z\"><\/path><\/svg><\/div><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">Cadeaux significatifs<\/h4><\/div><p class=\"uagb-ifb-desc\">Embrassez l'esprit de g\u00e9n\u00e9rosit\u00e9 avec nos cadeaux religieux soigneusement s\u00e9lectionn\u00e9s, qui v\u00e9hiculent sinc\u00e9rit\u00e9 et r\u00e9v\u00e9rence.<\/p><\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-uagb-container uagb-block-0875eb55 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-abcd4e61\">\n<div class=\"wp-block-uagb-info-box uagb-block-47b7c002 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">El\u00e9gance et symbolisme dans les cadeaux<\/h3><\/div><p class=\"uagb-ifb-desc\">D\u00e9couvrez le savoir-faire m\u00e9ticuleux de nos cand\u00e9labres de banc, lampes \u00e0 bougies, chevalets et vases, con\u00e7us pour ajouter \u00e9l\u00e9gance et symbolisme \u00e0 vos cadeaux religieux, parfaits pour les c\u00e9r\u00e9monies et les occasions spirituelles.<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-f837bf6f\">\n<div class=\"wp-block-uagb-container uagb-block-27788532\">\n<div class=\"wp-block-uagb-info-box uagb-block-ead7767b uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M438.6 105.4C451.1 117.9 451.1 138.1 438.6 150.6L182.6 406.6C170.1 419.1 149.9 419.1 137.4 406.6L9.372 278.6C-3.124 266.1-3.124 245.9 9.372 233.4C21.87 220.9 42.13 220.9 54.63 233.4L159.1 338.7L393.4 105.4C405.9 92.88 426.1 92.88 438.6 105.4H438.6z\"><\/path><\/svg><\/div><\/div><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">Artisanat et \u00e9l\u00e9gance<\/h4><\/div><p class=\"uagb-ifb-desc\">D\u00e9couvrez le savoir-faire artisanal de nos cadeaux spirituels, qui rehaussent la beaut\u00e9 et l'importance des c\u00e9r\u00e9monies religieuses et des monuments comm\u00e9moratifs.<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-200adade\">\n<div class=\"wp-block-uagb-info-box uagb-block-14c90ca5 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M438.6 105.4C451.1 117.9 451.1 138.1 438.6 150.6L182.6 406.6C170.1 419.1 149.9 419.1 137.4 406.6L9.372 278.6C-3.124 266.1-3.124 245.9 9.372 233.4C21.87 220.9 42.13 220.9 54.63 233.4L159.1 338.7L393.4 105.4C405.9 92.88 426.1 92.88 438.6 105.4H438.6z\"><\/path><\/svg><\/div><\/div><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">Dessins symboliques<\/h4><\/div><p class=\"uagb-ifb-desc\">Plongez dans la signification et l'art de nos cadeaux religieux, m\u00e9ticuleusement con\u00e7us pour transmettre des messages de foi et d'amour \u00e0 l'occasion de diverses manifestations spirituelles.<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-fd033695\">\n<div class=\"wp-block-uagb-info-box uagb-block-caa994d6 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-icon-wrap\"><div class=\"uagb-iconbox-icon-wrap uagb-infobox-shape-circle\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M438.6 105.4C451.1 117.9 451.1 138.1 438.6 150.6L182.6 406.6C170.1 419.1 149.9 419.1 137.4 406.6L9.372 278.6C-3.124 266.1-3.124 245.9 9.372 233.4C21.87 220.9 42.13 220.9 54.63 233.4L159.1 338.7L393.4 105.4C405.9 92.88 426.1 92.88 438.6 105.4H438.6z\"><\/path><\/svg><\/div><\/div><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">Cr\u00e9ations \u00e9l\u00e9gantes<\/h4><\/div><p class=\"uagb-ifb-desc\">Admirez l'\u00e9l\u00e9gance et la cr\u00e9ativit\u00e9 de nos paniers de condol\u00e9ances, de nos supports de plantes et de nos photophores, parfaits pour des gestes significatifs lors d'occasions sombres.<\/p><\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-uagb-container uagb-block-e8a2a613 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-51e2c002\">\n<div class=\"wp-block-uagb-info-box uagb-block-fc90a4a2 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h2 class=\"uagb-ifb-title\">Cat\u00e9gories florales<\/h2><\/div><p class=\"uagb-ifb-desc\">D\u00e9couvrez nos derni\u00e8res r\u00e9alisations et innovations dans nos cat\u00e9gories florales, o\u00f9 nous mettons en avant nos travaux les plus pointus.<\/p><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-f2f686c0\">\n<div class=\"wp-block-uagb-container uagb-block-03da51f9\">\n<div class=\"wp-block-uagb-container uagb-block-bca0ac81\">\n<div class=\"wp-block-uagb-image uagb-block-e4fcfe5f wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/natures-02.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/natures-02.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/natures-02.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/natures-02.jpg\" alt=\"\" class=\"uag-image-80574 lazyload\" width=\"282\" height=\"282\" title=\"natures-02\" loading=\"lazy\" role=\"img\"\/><noscript><img decoding=\"async\" srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/natures-02.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/natures-02.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/natures-02.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/natures-02.jpg\" alt=\"\" class=\"uag-image-80574 lazyload\" width=\"282\" height=\"282\" title=\"natures-02\" loading=\"lazy\" role=\"img\"\/><\/noscript><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-0a7ee55f wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-02.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-02.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-02.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-02.jpg\" alt=\"\" class=\"uag-image-80570 lazyload\" width=\"282\" height=\"282\" title=\"desserts-02\" loading=\"lazy\" role=\"img\"\/><noscript><img decoding=\"async\" srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-02.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-02.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-02.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-02.jpg\" alt=\"\" class=\"uag-image-80570 lazyload\" width=\"282\" height=\"282\" title=\"desserts-02\" loading=\"lazy\" role=\"img\"\/><\/noscript><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-42ebd4f6\">\n<div class=\"wp-block-uagb-image uagb-block-4a7f1049 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/snow-mountains-02.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/snow-mountains-02.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/snow-mountains-02.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/snow-mountains-02.jpg\" alt=\"\" class=\"uag-image-80578 lazyload\" width=\"282\" height=\"282\" title=\"montagnes de neige-02\" loading=\"lazy\" role=\"img\"\/><noscript><img decoding=\"async\" srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/snow-mountains-02.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/snow-mountains-02.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/snow-mountains-02.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/snow-mountains-02.jpg\" alt=\"\" class=\"uag-image-80578 lazyload\" width=\"282\" height=\"282\" title=\"montagnes de neige-02\" loading=\"lazy\" role=\"img\"\/><\/noscript><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-271d56c7 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/mountains-02.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/mountains-02.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/mountains-02.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/mountains-02.jpg\" alt=\"\" class=\"uag-image-80572 lazyload\" width=\"282\" height=\"282\" title=\"montagnes-02\" loading=\"lazy\" role=\"img\"\/><noscript><img decoding=\"async\" srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/mountains-02.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/mountains-02.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/mountains-02.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/mountains-02.jpg\" alt=\"\" class=\"uag-image-80572 lazyload\" width=\"282\" height=\"282\" title=\"montagnes-02\" loading=\"lazy\" role=\"img\"\/><\/noscript><\/figure><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-3560d1a5\">\n<div class=\"wp-block-uagb-container uagb-block-5894fa70\">\n<div class=\"wp-block-uagb-image uagb-block-6770cd95 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/rivers-02.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/rivers-02.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/rivers-02.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/rivers-02.jpg\" alt=\"\" class=\"uag-image-80576 lazyload\" width=\"282\" height=\"282\" title=\"rivi\u00e8res-02\" loading=\"lazy\" role=\"img\"\/><noscript><img decoding=\"async\" srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/rivers-02.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/rivers-02.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/rivers-02.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/rivers-02.jpg\" alt=\"\" class=\"uag-image-80576 lazyload\" width=\"282\" height=\"282\" title=\"rivi\u00e8res-02\" loading=\"lazy\" role=\"img\"\/><\/noscript><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-b201bcee wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/trees-02.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/trees-02.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/trees-02.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/trees-02.jpg\" alt=\"\" class=\"uag-image-80681 lazyload\" width=\"282\" height=\"282\" title=\"arbres-02\" loading=\"lazy\" role=\"img\"\/><noscript><img decoding=\"async\" srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/trees-02.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/trees-02.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/trees-02.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/trees-02.jpg\" alt=\"\" class=\"uag-image-80681 lazyload\" width=\"282\" height=\"282\" title=\"arbres-02\" loading=\"lazy\" role=\"img\"\/><\/noscript><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-0a3f9b21\">\n<div class=\"wp-block-uagb-image uagb-block-728c8074 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/09\/trees-rivers-02.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/09\/trees-rivers-02.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/09\/trees-rivers-02.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/09\/trees-rivers-02.jpg\" alt=\"\" class=\"uag-image-80698 lazyload\" width=\"282\" height=\"282\" title=\"arbres-rivers-02\" loading=\"lazy\" role=\"img\"\/><noscript><img decoding=\"async\" srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/09\/trees-rivers-02.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/09\/trees-rivers-02.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/09\/trees-rivers-02.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/09\/trees-rivers-02.jpg\" alt=\"\" class=\"uag-image-80698 lazyload\" width=\"282\" height=\"282\" title=\"arbres-rivers-02\" loading=\"lazy\" role=\"img\"\/><\/noscript><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-9206fcbd wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/natures-02.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/natures-02.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/natures-02.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/natures-02.jpg\" alt=\"\" class=\"uag-image-80574 lazyload\" width=\"282\" height=\"282\" title=\"natures-02\" loading=\"lazy\" role=\"img\"\/><noscript><img decoding=\"async\" srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/natures-02.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/natures-02.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/natures-02.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/natures-02.jpg\" alt=\"\" class=\"uag-image-80574 lazyload\" width=\"282\" height=\"282\" title=\"natures-02\" loading=\"lazy\" role=\"img\"\/><\/noscript><\/figure><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-uagb-container uagb-block-7904eaf3 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-info-box uagb-block-18e6815d uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h2 class=\"uagb-ifb-title\">Chefs-d'\u0153uvre floraux<\/h2><\/div><p class=\"uagb-ifb-desc\">Explorez notre galerie remplie de motifs floraux exquis, parfaits pour vos arrangements de cadeaux religieux.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-ec11566e\">\n<div class=\"wp-block-uagb-container uagb-block-08bf843c\">\n<div class=\"wp-block-uagb-container uagb-block-920cad8c\">\n<div class=\"wp-block-uagb-image alignleft uagb-block-5bb0bbc0 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/natures-01-1024x683.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/09\/gallery-10.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/09\/gallery-10.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/natures-01-1024x683.jpg\" alt=\"\" class=\"uag-image-80573 lazyload\" width=\"792\" height=\"446\" title=\"\" loading=\"lazy\"\/><noscript><img decoding=\"async\" srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/natures-01-1024x683.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/09\/gallery-10.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/09\/gallery-10.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/natures-01-1024x683.jpg\" alt=\"\" class=\"uag-image-80573 lazyload\" width=\"792\" height=\"446\" title=\"\" loading=\"lazy\"\/><\/noscript><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-e0323075\">\n<div class=\"wp-block-uagb-image alignleft uagb-block-9cbc911a wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-02.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/09\/gallery-27.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/09\/gallery-27.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-02.jpg\" alt=\"\" class=\"uag-image-80570 lazyload\" width=\"400\" height=\"446\" title=\"\" loading=\"lazy\"\/><noscript><img decoding=\"async\" srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-02.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/09\/gallery-27.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/09\/gallery-27.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-02.jpg\" alt=\"\" class=\"uag-image-80570 lazyload\" width=\"400\" height=\"446\" title=\"\" loading=\"lazy\"\/><\/noscript><\/figure><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-01bd5354\">\n<div class=\"wp-block-uagb-container uagb-block-aa24ab14\">\n<div class=\"wp-block-uagb-image alignleft uagb-block-df48cc3c wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/snow-mountains-02.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/09\/gallery-28.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/09\/gallery-28-257x300.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/snow-mountains-02.jpg\" alt=\"\" class=\"uag-image-80578 lazyload\" width=\"400\" height=\"466\" title=\"\" loading=\"lazy\"\/><noscript><img decoding=\"async\" srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/snow-mountains-02.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/09\/gallery-28.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/09\/gallery-28-257x300.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/snow-mountains-02.jpg\" alt=\"\" class=\"uag-image-80578 lazyload\" width=\"400\" height=\"466\" title=\"\" loading=\"lazy\"\/><\/noscript><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-c6438229\">\n<div class=\"wp-block-uagb-image alignleft uagb-block-34281fbc wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/mountains-01-1024x683.jpg , https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/mountains-01.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/mountains-01-1024x683.jpg\" alt=\"\" class=\"uag-image-80571 lazyload\" width=\"792\" height=\"466\" title=\"\" loading=\"lazy\"\/><noscript><img decoding=\"async\" srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/mountains-01-1024x683.jpg , https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/mountains-01.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/mountains-01-1024x683.jpg\" alt=\"\" class=\"uag-image-80571 lazyload\" width=\"792\" height=\"466\" title=\"\" loading=\"lazy\"\/><\/noscript><\/figure><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-uagb-container uagb-block-a37cb94d alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-02b2643c\">\n<div class=\"wp-block-uagb-info-box uagb-block-cf9e68d1 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h2 class=\"uagb-ifb-title\">Pourquoi choisir Blumenhandler Florist pour des cadeaux religieux ?<\/h2><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-0db1fe01\">\n<div class=\"wp-block-uagb-info-box uagb-block-c5887fb5 uagb-infobox__content-wrap  uagb-infobox-icon-left-title uagb-infobox-left uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-left-title-image\"><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">Service de qualit\u00e9<\/h4><\/div><\/div><p class=\"uagb-ifb-desc\">Notre \u00e9quipe garantit une qualit\u00e9 sup\u00e9rieure et un excellent service \u00e0 la client\u00e8le, avec une large gamme d'arrangements religieux uniques.<\/p><div class=\"uagb-ifb-separator\"><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-8320b8f4 uagb-infobox__content-wrap  uagb-infobox-icon-left-title uagb-infobox-left uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-left-title-image\"><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">Offres uniques<\/h4><\/div><\/div><p class=\"uagb-ifb-desc\">Des solutions personnalis\u00e9es adapt\u00e9es \u00e0 vos besoins, offrant une s\u00e9lection vari\u00e9e de cadeaux religieux significatifs pour diverses occasions et c\u00e9r\u00e9monies.<\/p><div class=\"uagb-ifb-separator\"><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-26acf763 uagb-infobox__content-wrap  uagb-infobox-icon-left-title uagb-infobox-left uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-left-title-image\"><div class=\"uagb-ifb-title-wrap\"><h4 class=\"uagb-ifb-title\">Service rapide<\/h4><\/div><\/div><p class=\"uagb-ifb-desc\">Comptez sur nous pour une livraison rapide afin que vos cadeaux religieux arrivent au moment o\u00f9 vous en avez le plus besoin.<\/p><div class=\"uagb-ifb-separator\"><\/div><\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-25055c6b\">\n<div class=\"wp-block-uagb-image alignleft uagb-block-2b404dfd wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" data-srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-01-1024x683.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-01.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-01.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-01-1024x683.jpg\" alt=\"\" class=\"uag-image-80569 lazyload\" width=\"564\" height=\"500\" title=\"\" loading=\"lazy\" role=\"img\"\/><noscript><img decoding=\"async\" srcset=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-01-1024x683.jpg ,https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-01.jpg 780w, https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-01.jpg 360w\" sizes=\"(max-width: 480px) 150px\" src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/desserts-01-1024x683.jpg\" alt=\"\" class=\"uag-image-80569 lazyload\" width=\"564\" height=\"500\" title=\"\" loading=\"lazy\" role=\"img\"\/><\/noscript><\/figure><\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-uagb-container uagb-block-45f809f9 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-info-box uagb-block-25ee98b8 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h6 class=\"uagb-ifb-title-prefix\">Commentaires<\/h6><h2 class=\"uagb-ifb-title\">T\u00e9moignages de clients<\/h2><\/div><p class=\"uagb-ifb-desc\">D\u00e9couvrez les r\u00e9cits sinc\u00e8res de clients satisfaits qui ont trouv\u00e9 leur bonheur dans nos cr\u00e9ations florales.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-f9770f2e\">\n<div class=\"wp-block-uagb-container uagb-block-a49f2642\">\n<div class=\"wp-block-uagb-star-rating uagb-block-9d745acf\"><div class=\"uag-star-rating\" title=\"5\/5\"><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-5f444e21 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><\/div><p class=\"uagb-ifb-desc\">J'ai \u00e9t\u00e9 ravie du service exceptionnel fourni par Blumenhandler Florist ! Leur d\u00e9vouement et leurs magnifiques arrangements ont d\u00e9pass\u00e9 mes attentes.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-7454da29 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" class=\"lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/testimonial-skip-06.jpg\" alt=\"\" width=\"48\" height=\"48\" loading=\"lazy\"\/><noscript><img decoding=\"async\" class=\"lazyload\" src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/testimonial-skip-06.jpg\" alt=\"\" width=\"48\" height=\"48\" loading=\"lazy\"\/><\/noscript><\/div><div class=\"uagb-ifb-title-wrap\"><h6 class=\"uagb-ifb-title\">Sophia Adams<\/h6><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-99ee0dee\">\n<div class=\"wp-block-uagb-star-rating uagb-block-ad6b7748\"><div class=\"uag-star-rating\" title=\"5\/5\"><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-73e5f556 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><\/div><p class=\"uagb-ifb-desc\">Je suis toujours impressionn\u00e9 par le professionnalisme et la qualit\u00e9 de Blumenhandler Florist. Ils ne d\u00e9\u00e7oivent jamais.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-833bbe7c uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" class=\"lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/testimonial-skip-13.jpg\" alt=\"\" width=\"48\" height=\"48\" loading=\"lazy\"\/><noscript><img decoding=\"async\" class=\"lazyload\" src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/testimonial-skip-13.jpg\" alt=\"\" width=\"48\" height=\"48\" loading=\"lazy\"\/><\/noscript><\/div><div class=\"uagb-ifb-title-wrap\"><h6 class=\"uagb-ifb-title\">Ethan Parker<\/h6><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-bb3b162c\">\n<div class=\"wp-block-uagb-star-rating uagb-block-d648d115\"><div class=\"uag-star-rating\" title=\"5\/5\"><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><span class=\"uag-star\">\u2605<\/span><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-3c7b265c uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><\/div><p class=\"uagb-ifb-desc\">Exceptionnellement fiable et digne d'\u00e9loges ! Je ne saurais trop recommander Blumenhandler Florist pour son excellence.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-info-box uagb-block-6bf5fe2a uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-image-content\"><img decoding=\"async\" class=\"lazyload\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/testimonial-skip-07.jpg\" alt=\"\" width=\"48\" height=\"48\" loading=\"lazy\"\/><noscript><img decoding=\"async\" class=\"lazyload\" src=\"https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/testimonial-skip-07.jpg\" alt=\"\" width=\"48\" height=\"48\" loading=\"lazy\"\/><\/noscript><\/div><div class=\"uagb-ifb-title-wrap\"><h6 class=\"uagb-ifb-title\">Ava Clark<\/h6><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-uagb-container uagb-block-6d512f26 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-fdda76b5\">\n<div class=\"wp-block-uagb-info-box uagb-block-864d55c6 uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h3 class=\"uagb-ifb-title\">Ornez vos moments privil\u00e9gi\u00e9s avec des cr\u00e9ations florales \u00e0 couper le souffle - contactez-nous d\u00e8s maintenant !<\/h3><\/div><\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-5b8040ed\">\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-d7d98968\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap\">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-7e0ed373 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\"><div class=\"uagb-button__link\">Nous contacter<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-13","page","type-page","status-publish","hentry"],"spectra_custom_meta":{"_uag_page_assets":["a:9:{s:3:\"css\";s:554142:\".wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:0.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}\n.uagb-ifb-content>svg *{-webkit-transition:all 0.2s;-o-transition:all 0.2s;transition:all 0.2s}.uagb-ifb-content>svg,.uagb-ifb-content{display:inline-block}.uagb-ifb-content>svg{vertical-align:middle;width:inherit;height:inherit;font-style:initial}.uagb-ifb-content .uagb-ifb-icon-wrap svg{box-sizing:content-box;width:inherit;height:inherit}.uagb-ifb-button-wrapper:empty{display:none}div.uagb-ifb-button-wrapper a.uagb-infobox-cta-link,div.uagb-ifb-cta a.uagb-infobox-cta-link,.entry .entry-content a.uagb-infobox-cta-link,a.uagb-infobox-link-wrap,.entry .entry-content a.uagb-infobox-link-wrap{text-decoration:none;align-items:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-middle .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-middle .uagb-ifb-content{-ms-flex-item-align:center;-webkit-align-self:center;align-self:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-image-valign-top .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-top .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-top .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-top .uagb-ifb-content{-webkit-align-self:self-start;align-self:self-start}.uagb-infobox-left{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-center{justify-content:center;text-align:center;-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center}.uagb-infobox-right{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}.uagb-infobox-icon-above-title.uagb-infobox__content-wrap,.uagb-infobox-icon-below-title.uagb-infobox__content-wrap{display:block;width:100%}.uagb-infobox-icon-left-title .uagb-ifb-content>svg,.uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:10px}.uagb-infobox-icon-right-title .uagb-ifb-content>svg,.uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:10px}.uagb-infobox-icon-left.uagb-infobox__content-wrap,.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:-webkit-flex;display:-moz-box;display:flex;-js-display:flex}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-image-content,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-image-content,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{flex-shrink:0;line-height:0}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-left .uagb-ifb-content,.uagb-infobox-icon-right .uagb-ifb-content{flex-grow:1}.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}.uagb-ifb-content img{position:relative;display:inline-block;line-height:0;width:auto;height:auto !important;max-width:100%;border-radius:inherit;-webkit-box-sizing:content-box;-moz-box-sizing:content-box;-webkit-border-radius:inherit}.uagb-infobox-module-link{position:absolute;top:0;right:0;bottom:0;left:0;z-index:4;width:100%;height:100%}.uagb-edit-mode .uagb-infobox-module-link{z-index:2}.uagb-infobox-link-icon-after{margin-right:0;margin-left:5px}.uagb-infobox-link-icon-before{margin-right:5px;margin-left:0}.uagb-infobox-link-icon{-webkit-transition:all 200ms linear;transition:all 200ms linear}.uagb-infobox__content-wrap{box-sizing:border-box;position:relative;width:100%;word-break:break-word;z-index:1}.uagb-ifb-separator{display:inline-block;margin:0;border-top-color:#333;border-top-style:solid;border-top-width:2px;line-height:0}.uagb-ifb-button-wrapper{line-height:1}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link{background-color:unset;border:none}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link:hover{background-color:unset;border-color:unset}.uagb-ifb-button-wrapper .uagb-infobox-cta-link{cursor:pointer}.uagb-ifb-button-wrapper .wp-block-button__link svg,.uagb-ifb-button-wrapper .ast-outline-button svg{fill:currentColor}.uagb-infobox__content-wrap a{-webkit-box-shadow:none;box-shadow:none;text-decoration:none}.uagb-ifb-title-wrap{width:100%}.uagb-ifb-title{margin-block-start:0}.uagb-ifb-title-wrap .uagb-ifb-title-prefix{display:block;padding:0;margin:0}.uagb-infobox__content-wrap.uagb-infobox__content-wrap{position:relative}.uagb-ifb-content{width:100%}.uagb-infobox__content-wrap.uagb-infobox,.uagb-ifb-content,.uagb-ifb-title-wrap,.uagb-ifb-title-prefix *,svg.dashicon.dashicons-upload{z-index:1}a.uagb-infobox-link-wrap{color:inherit}.uagb-ifb-content p:empty{display:none}.uagb-infobox__content-wrap .uagb-ifb-content img{display:inline-block;max-width:100%}.uagb-infobox__content-wrap .uagb-ifb-content svg{display:inline-block}.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{box-sizing:content-box}.uagb-infobox-cta-link>svg{vertical-align:middle;width:15px;height:15px;font-size:15px}.uagb-infobox-cta-link{display:inline-flex}.block-editor-page #wpwrap .uagb-infobox-cta-link svg,.uagb-infobox-cta-link svg{font-style:normal}.uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}.uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}.uagb-infobox-icon-left .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:flex}.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}a.uagb-infbox__link-to-all{position:absolute;top:0;left:0;z-index:3;width:100%;height:100%;box-shadow:none;text-decoration:none;-webkit-box-shadow:none}@media only screen and (max-width: 976px){.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{padding:0;margin-bottom:20px}.uagb-infobox-stacked-tablet.uagb-reverse-order-tablet.uagb-infobox__content-wrap{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-content,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{display:block;width:100%;text-align:center}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{margin-right:0;margin-left:0}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}@media screen and (max-width: 767px){.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap{padding:0;margin-bottom:20px;margin-right:0;margin-left:0}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap.uagb-reverse-order-mobile{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-content{display:block;width:100%;text-align:center}.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}.uagb-ifb-icon svg{width:inherit;height:inherit;vertical-align:middle}.uagb-ifb-button-icon{height:15px;width:15px;font-size:15px;vertical-align:middle}.uagb-ifb-button-icon svg{height:inherit;width:inherit;display:inline-block}.uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:right}.uagb-ifb-cta-button{display:inline-block}.uagb-disable-link{pointer-events:none}@media only screen and (min-width: 977px){.uagb-infobox-margin-wrapper{display:flex}}.uagb-ifb-content .uagb-ifb-desc p:last-child{margin-bottom:0}\n.uagb-buttons__outer-wrap .uagb-buttons__wrap{display:inline-flex;width:100%}.uagb-buttons__outer-wrap.uagb-btn__small-btn .uagb-buttons-repeater{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn__medium-btn .uagb-buttons-repeater{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn__large-btn .uagb-buttons-repeater{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn__extralarge-btn .uagb-buttons-repeater{padding:30px 65px}@media (max-width: 976px){.uagb-buttons__outer-wrap.uagb-btn-tablet__small-btn .uagb-buttons-repeater{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn-tablet__medium-btn .uagb-buttons-repeater{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn-tablet__large-btn .uagb-buttons-repeater{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn-tablet__extralarge-btn .uagb-buttons-repeater{padding:30px 65px}}@media (max-width: 767px){.uagb-buttons__outer-wrap.uagb-btn-mobile__small-btn .uagb-buttons-repeater{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn-mobile__medium-btn .uagb-buttons-repeater{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn-mobile__large-btn .uagb-buttons-repeater{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn-mobile__extralarge-btn .uagb-buttons-repeater{padding:30px 65px}}\n.uagb-buttons__outer-wrap .uagb-buttons-repeater{display:flex;justify-content:center;align-items:center;transition:box-shadow 0.2s ease}.uagb-buttons__outer-wrap .uagb-buttons-repeater a.uagb-button__link{display:flex;justify-content:center}.uagb-buttons__outer-wrap .uagb-buttons-repeater .uagb-button__icon{font-size:inherit;display:flex;align-items:center}.uagb-buttons__outer-wrap .uagb-buttons-repeater .uagb-button__icon svg{fill:currentColor;width:inherit;height:inherit}\n.wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow 0.2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:0.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:0.2;background:rgba(0,0,0,0.5);transition:opacity 0.35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:0.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform 0.35s, opacity 0.35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform 0.4s, opacity 0.4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform 0.45s, opacity 0.45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform 0.35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform 0.35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:0.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:0.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}\n.wp-block-uagb-star-rating{display:flex}.wp-block-uagb-star-rating .uag-star-rating__title{margin:0}.wp-block-uagb-star-rating .uag-star-rating{display:flex;align-items:center}.wp-block-uagb-star-rating .uag-star{color:#ccd6df;display:inline-block;line-height:0.75em}\n.wp-block-uagb-container.uagb-block-5657136f .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5657136f .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5657136f .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5657136f .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5657136f .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5657136f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5657136f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 800px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-5657136f{box-shadow: 0px 0px   #00000070 ;padding-top: 112px;padding-bottom: 112px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-5);;row-gap: 0px;column-gap: 0px;}.uagb-block-48b77c69 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-48b77c69 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-48b77c69 .uagb-ifb-icon svg{fill: #333;}.uagb-block-48b77c69.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-48b77c69 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-48b77c69 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-48b77c69.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-48b77c69.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-48b77c69 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-48b77c69 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-48b77c69 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-48b77c69 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-48b77c69.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-48b77c69.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-48b77c69.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-48b77c69.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-48b77c69 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-48b77c69.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 24px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-48b77c69.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-3);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-48b77c69 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-48b77c69 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-48b77c69 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-48b77c69 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-48b77c69.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-48b77c69.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-48b77c69 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-48b77c69.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-48b77c69.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-48b77c69.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-48b77c69.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-block-8c4383c7 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8c4383c7 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8c4383c7 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8c4383c7 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8c4383c7 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8c4383c7{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8c4383c7 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 72px;}.wp-block-uagb-container.uagb-block-8c4383c7{box-shadow: 0px 0px   #00000070 ;padding-top: 112px;padding-bottom: 112px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-5);;row-gap: 0px;column-gap: 72px;}.wp-block-uagb-container.uagb-block-d4a03254 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d4a03254 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d4a03254 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d4a03254 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d4a03254 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d4a03254{max-width: 55%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d4a03254 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 32px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-d4a03254{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 32px;column-gap: 0px;}.uagb-block-7edef7ac .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-7edef7ac .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-7edef7ac .uagb-ifb-icon svg{fill: #333;}.uagb-block-7edef7ac.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-7edef7ac .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-7edef7ac .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7edef7ac.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7edef7ac.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7edef7ac .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-7edef7ac .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-7edef7ac .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7edef7ac .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-7edef7ac.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-7edef7ac.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-7edef7ac.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-7edef7ac.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-7edef7ac .uagb-ifb-title-wrap .uagb-ifb-title-prefix{color: var(--ast-global-color-2);margin-bottom: 24px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-7edef7ac.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-7edef7ac.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-3);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-7edef7ac .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-7edef7ac .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-7edef7ac .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-7edef7ac .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-7edef7ac.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-7edef7ac.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-7edef7ac .uagb-infobox__content-wrap{text-align: left;}.uagb-block-7edef7ac.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-7edef7ac.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-7edef7ac.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-7edef7ac.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-5b4bff5d.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-5b4bff5d.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.wp-block-uagb-buttons .uagb-block-de3d4e0e .wp-block-button__link{background: transparent;}.wp-block-uagb-buttons .uagb-block-de3d4e0e .wp-block-button__link:hover{background: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-de3d4e0e .wp-block-button__link:focus{background: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-de3d4e0e .uagb-button__wrapper .uagb-buttons-repeater{color: var(--ast-global-color-2);margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-de3d4e0e .wp-block-button__link.has-text-color:hover .uagb-button__link{color: #ffffff;}.wp-block-uagb-buttons .uagb-block-de3d4e0e .wp-block-button__link.has-text-color:focus .uagb-button__link{color: #ffffff;}.wp-block-uagb-buttons .uagb-block-de3d4e0e .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-de3d4e0e .uagb-buttons-repeater.wp-block-button__link{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 4px;border-top-right-radius: 4px;border-bottom-left-radius: 4px;border-bottom-right-radius: 4px;border-color: var(--ast-global-color-2);border-style: solid;}.wp-block-uagb-buttons .uagb-block-de3d4e0e .uagb-buttons-repeater.wp-block-button__link:hover{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-de3d4e0e .uagb-buttons-repeater.wp-block-button__link:focus{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-de3d4e0e.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 4px;border-top-right-radius: 4px;border-bottom-left-radius: 4px;border-bottom-right-radius: 4px;border-color: var(--ast-global-color-2);border-style: solid;}.wp-block-uagb-buttons .uagb-block-de3d4e0e.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-de3d4e0e .uagb-buttons-repeater .uagb-button__link{color: var(--ast-global-color-2);}.wp-block-uagb-buttons .uagb-block-de3d4e0e .uagb-buttons-repeater:hover .uagb-button__link{color: #ffffff;}.wp-block-uagb-buttons .uagb-block-de3d4e0e .uagb-buttons-repeater:focus .uagb-button__link{color: #ffffff;}.wp-block-uagb-buttons .uagb-block-de3d4e0e .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: var(--ast-global-color-2);}.wp-block-uagb-buttons .uagb-block-de3d4e0e .uagb-buttons-repeater:hover .uagb-button__icon > svg{fill: #ffffff;}.wp-block-uagb-buttons .uagb-block-de3d4e0e .uagb-buttons-repeater:focus .uagb-button__icon > svg{fill: #ffffff;}.wp-block-uagb-buttons .uagb-block-de3d4e0e .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-de3d4e0e .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-de3d4e0e .uagb-button__link{text-transform: normal;text-decoration: none;}.wp-block-uagb-container.uagb-block-699445d0 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-699445d0 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-699445d0 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-699445d0 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-699445d0 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-699445d0{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-699445d0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 24px;}.wp-block-uagb-container.uagb-block-699445d0{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 24px;}.wp-block-uagb-container.uagb-block-230a853e .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-230a853e .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-230a853e .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-230a853e .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-230a853e .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-230a853e{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-230a853e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-end;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-230a853e{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 50px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: flex-end;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-1bc337b7.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-1bc337b7 .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-1bc337b7.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-1bc337b7.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-1bc337b7.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-1bc337b7.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-1bc337b7.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-1bc337b7.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-1bc337b7.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-1bc337b7.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-1bc337b7.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-1bc337b7.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-1bc337b7.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 270px;height: 360px;}.uagb-block-1bc337b7.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-1bc337b7.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-1bc337b7.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-1bc337b7.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-9f131a21 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9f131a21 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9f131a21 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9f131a21 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9f131a21 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9f131a21{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9f131a21 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-end;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-9f131a21{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: flex-end;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-7482949b.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-7482949b .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-7482949b.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-7482949b.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-7482949b.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-7482949b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-7482949b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-7482949b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-7482949b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-7482949b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-7482949b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-7482949b.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-7482949b.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 270px;height: 360px;}.uagb-block-7482949b.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-7482949b.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-7482949b.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-7482949b.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-323c7320 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-323c7320 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-323c7320 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-323c7320 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-323c7320 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-323c7320{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-323c7320 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 72px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-323c7320{box-shadow: 0px 0px   #00000070 ;padding-top: 112px;padding-bottom: 112px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-5);;row-gap: 72px;column-gap: 0px;}.uagb-block-9fbe867d .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-9fbe867d .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-9fbe867d .uagb-ifb-icon svg{fill: #333;}.uagb-block-9fbe867d.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-9fbe867d .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-9fbe867d .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-9fbe867d.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-9fbe867d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-9fbe867d .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-9fbe867d .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-9fbe867d .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-9fbe867d .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-9fbe867d.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-9fbe867d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-9fbe867d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-9fbe867d.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-9fbe867d .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-9fbe867d.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-9fbe867d.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-3);margin-bottom: 0%;margin-top: 0%;margin-left: 15%;margin-right: 15%;}.uagb-block-9fbe867d .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-9fbe867d .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-9fbe867d .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-9fbe867d .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-9fbe867d.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-9fbe867d.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-9fbe867d .uagb-infobox__content-wrap{text-align: center;}.uagb-block-9fbe867d.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-9fbe867d.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-9fbe867d.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-9fbe867d.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-block-682319ac .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-682319ac .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-682319ac .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-682319ac .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-682319ac .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-682319ac{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-682319ac > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 48px;}.wp-block-uagb-container.uagb-block-682319ac{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 48px;}.wp-block-uagb-container.uagb-block-71e8fff3 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-71e8fff3 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-71e8fff3 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-71e8fff3 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-71e8fff3 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-71e8fff3{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-71e8fff3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: stretch;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-71e8fff3{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-color: inherit;background-color: ;;flex-direction: column;align-items: stretch;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-75ccde33.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-75ccde33 .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-75ccde33.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-75ccde33.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-75ccde33.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-75ccde33.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-75ccde33.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-75ccde33.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-75ccde33.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-75ccde33.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-75ccde33.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-75ccde33.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-75ccde33.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 368px;height: 450px;}.uagb-block-75ccde33.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-75ccde33.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-75ccde33.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-75ccde33.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-9ee67bb3 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9ee67bb3 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9ee67bb3 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9ee67bb3 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9ee67bb3 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9ee67bb3{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9ee67bb3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 28px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-9ee67bb3{box-shadow: 0px 0px   #00000070 ;padding-top: 20px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-color: inherit;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 28px;column-gap: 0px;}.uagb-block-2ab09e50 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-2ab09e50 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-2ab09e50 .uagb-ifb-icon svg{fill: #333;}.uagb-block-2ab09e50.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-2ab09e50 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-2ab09e50 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-2ab09e50.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-2ab09e50.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-2ab09e50 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-2ab09e50 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-2ab09e50 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-2ab09e50 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-2ab09e50.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-2ab09e50.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-2ab09e50.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-2ab09e50.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-2ab09e50 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-2ab09e50.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 16px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-2ab09e50.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-3);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-2ab09e50 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-2ab09e50 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-2ab09e50 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-2ab09e50 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-2ab09e50.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-2ab09e50.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-2ab09e50 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-2ab09e50.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-2ab09e50.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-2ab09e50.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-2ab09e50.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-64373be9.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 0px;}.uagb-block-64373be9.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.wp-block-uagb-buttons .uagb-block-15570a3f .wp-block-button__link{background: transparent;}.wp-block-uagb-buttons .uagb-block-15570a3f .wp-block-button__link:hover{background: transparent;}.wp-block-uagb-buttons .uagb-block-15570a3f .wp-block-button__link:focus{background: transparent;}.wp-block-uagb-buttons .uagb-block-15570a3f .uagb-button__wrapper .uagb-buttons-repeater{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;color: var(--ast-global-color-2);margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-15570a3f .wp-block-button__link.has-text-color:hover .uagb-button__link{color: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-15570a3f .wp-block-button__link.has-text-color:focus .uagb-button__link{color: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-15570a3f .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-15570a3f .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-15570a3f .uagb-buttons-repeater .uagb-button__link{color: var(--ast-global-color-2);}.wp-block-uagb-buttons .uagb-block-15570a3f .uagb-buttons-repeater:hover .uagb-button__link{color: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-15570a3f .uagb-buttons-repeater:focus .uagb-button__link{color: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-15570a3f .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: var(--ast-global-color-2);}.wp-block-uagb-buttons .uagb-block-15570a3f .uagb-buttons-repeater:hover .uagb-button__icon > svg{fill: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-15570a3f .uagb-buttons-repeater:focus .uagb-button__icon > svg{fill: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-15570a3f .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-15570a3f .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-15570a3f .uagb-button__link{text-transform: normal;text-decoration: none;}.wp-block-uagb-container.uagb-block-a767bc2d .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a767bc2d .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a767bc2d .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a767bc2d .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a767bc2d .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a767bc2d{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a767bc2d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: stretch;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-a767bc2d{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-color: inherit;background-color: ;;flex-direction: column;align-items: stretch;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-b2504f0e.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-b2504f0e .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-b2504f0e.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-b2504f0e.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-b2504f0e.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-b2504f0e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-b2504f0e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-b2504f0e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-b2504f0e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-b2504f0e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-b2504f0e.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-b2504f0e.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-b2504f0e.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 368px;height: 450px;}.uagb-block-b2504f0e.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-b2504f0e.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-b2504f0e.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-b2504f0e.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-9aef83d0 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9aef83d0 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9aef83d0 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9aef83d0 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9aef83d0 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9aef83d0{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9aef83d0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 28px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-9aef83d0{box-shadow: 0px 0px   #00000070 ;padding-top: 20px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-color: inherit;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 28px;column-gap: 0px;}.uagb-block-7e10dc31 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-7e10dc31 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-7e10dc31 .uagb-ifb-icon svg{fill: #333;}.uagb-block-7e10dc31.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-7e10dc31 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-7e10dc31 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7e10dc31.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7e10dc31.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7e10dc31 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-7e10dc31 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-7e10dc31 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7e10dc31 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-7e10dc31.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-7e10dc31.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-7e10dc31.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-7e10dc31.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-7e10dc31 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-7e10dc31.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 16px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-7e10dc31.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-3);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-7e10dc31 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-7e10dc31 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-7e10dc31 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-7e10dc31 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-7e10dc31.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-7e10dc31.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-7e10dc31 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-7e10dc31.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-7e10dc31.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-7e10dc31.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-7e10dc31.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-66047323.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 0px;}.uagb-block-66047323.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.wp-block-uagb-buttons .uagb-block-5658abd4 .wp-block-button__link{background: transparent;}.wp-block-uagb-buttons .uagb-block-5658abd4 .wp-block-button__link:hover{background: transparent;}.wp-block-uagb-buttons .uagb-block-5658abd4 .wp-block-button__link:focus{background: transparent;}.wp-block-uagb-buttons .uagb-block-5658abd4 .uagb-button__wrapper .uagb-buttons-repeater{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;color: var(--ast-global-color-2);margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-5658abd4 .wp-block-button__link.has-text-color:hover .uagb-button__link{color: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-5658abd4 .wp-block-button__link.has-text-color:focus .uagb-button__link{color: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-5658abd4 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-5658abd4 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-5658abd4 .uagb-buttons-repeater .uagb-button__link{color: var(--ast-global-color-2);}.wp-block-uagb-buttons .uagb-block-5658abd4 .uagb-buttons-repeater:hover .uagb-button__link{color: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-5658abd4 .uagb-buttons-repeater:focus .uagb-button__link{color: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-5658abd4 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: var(--ast-global-color-2);}.wp-block-uagb-buttons .uagb-block-5658abd4 .uagb-buttons-repeater:hover .uagb-button__icon > svg{fill: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-5658abd4 .uagb-buttons-repeater:focus .uagb-button__icon > svg{fill: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-5658abd4 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-5658abd4 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-5658abd4 .uagb-button__link{text-transform: normal;text-decoration: none;}.wp-block-uagb-container.uagb-block-1add9e25 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1add9e25 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1add9e25 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1add9e25 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1add9e25 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1add9e25{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1add9e25 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: stretch;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-1add9e25{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-color: inherit;background-color: ;;flex-direction: column;align-items: stretch;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-cf6d3a59.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-cf6d3a59 .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-cf6d3a59.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-cf6d3a59.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-cf6d3a59.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-cf6d3a59.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-cf6d3a59.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-cf6d3a59.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-cf6d3a59.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-cf6d3a59.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-cf6d3a59.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-cf6d3a59.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-cf6d3a59.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 368px;height: 450px;}.uagb-block-cf6d3a59.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-cf6d3a59.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-cf6d3a59.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-cf6d3a59.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-8e1bc111 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8e1bc111 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8e1bc111 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8e1bc111 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8e1bc111 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8e1bc111{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8e1bc111 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 28px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-8e1bc111{box-shadow: 0px 0px   #00000070 ;padding-top: 20px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-color: inherit;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 28px;column-gap: 0px;}.uagb-block-3ce36a5e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-3ce36a5e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-3ce36a5e .uagb-ifb-icon svg{fill: #333;}.uagb-block-3ce36a5e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3ce36a5e .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3ce36a5e .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3ce36a5e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3ce36a5e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3ce36a5e .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3ce36a5e .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3ce36a5e .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3ce36a5e .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-3ce36a5e.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3ce36a5e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3ce36a5e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3ce36a5e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3ce36a5e .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-3ce36a5e.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 16px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-3ce36a5e.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-3);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-3ce36a5e .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-3ce36a5e .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-3ce36a5e .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-3ce36a5e .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-3ce36a5e.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-3ce36a5e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-3ce36a5e .uagb-infobox__content-wrap{text-align: left;}.uagb-block-3ce36a5e.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-3ce36a5e.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-3ce36a5e.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-3ce36a5e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-7e724e0b.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 0px;}.uagb-block-7e724e0b.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.wp-block-uagb-buttons .uagb-block-a3d0307e .wp-block-button__link{background: transparent;}.wp-block-uagb-buttons .uagb-block-a3d0307e .wp-block-button__link:hover{background: transparent;}.wp-block-uagb-buttons .uagb-block-a3d0307e .wp-block-button__link:focus{background: transparent;}.wp-block-uagb-buttons .uagb-block-a3d0307e .uagb-button__wrapper .uagb-buttons-repeater{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;color: var(--ast-global-color-2);margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-a3d0307e .wp-block-button__link.has-text-color:hover .uagb-button__link{color: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-a3d0307e .wp-block-button__link.has-text-color:focus .uagb-button__link{color: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-a3d0307e .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-a3d0307e .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-a3d0307e .uagb-buttons-repeater .uagb-button__link{color: var(--ast-global-color-2);}.wp-block-uagb-buttons .uagb-block-a3d0307e .uagb-buttons-repeater:hover .uagb-button__link{color: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-a3d0307e .uagb-buttons-repeater:focus .uagb-button__link{color: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-a3d0307e .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: var(--ast-global-color-2);}.wp-block-uagb-buttons .uagb-block-a3d0307e .uagb-buttons-repeater:hover .uagb-button__icon > svg{fill: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-a3d0307e .uagb-buttons-repeater:focus .uagb-button__icon > svg{fill: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-a3d0307e .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-a3d0307e .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-a3d0307e .uagb-button__link{text-transform: normal;text-decoration: none;}.wp-block-uagb-container.uagb-block-1202b3b6 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1202b3b6 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1202b3b6 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1202b3b6 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1202b3b6 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1202b3b6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1202b3b6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 48px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-1202b3b6{box-shadow: 0px 0px   #00000070 ;padding-top: 112px;padding-bottom: 112px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-5);;row-gap: 48px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-f854eaf6 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f854eaf6 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f854eaf6 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f854eaf6 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f854eaf6 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f854eaf6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f854eaf6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 72px;}.wp-block-uagb-container.uagb-block-f854eaf6{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 72px;}.uagb-block-4f577d90 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-4f577d90 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-4f577d90 .uagb-ifb-icon svg{fill: #333;}.uagb-block-4f577d90.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-4f577d90 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-4f577d90 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-4f577d90.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-4f577d90.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-4f577d90 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-4f577d90 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-4f577d90 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-4f577d90 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-4f577d90.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-4f577d90.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-4f577d90.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-4f577d90.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-4f577d90 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-4f577d90.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-4f577d90.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-4f577d90 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-4f577d90 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-4f577d90 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-4f577d90 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-4f577d90.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-4f577d90.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-4f577d90 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-4f577d90.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-4f577d90.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-4f577d90.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-4f577d90.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-fdb34588 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-fdb34588 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-fdb34588 .uagb-ifb-icon svg{fill: #333;}.uagb-block-fdb34588.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-fdb34588 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-fdb34588 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fdb34588.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fdb34588.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fdb34588 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-fdb34588 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-fdb34588 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fdb34588 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-fdb34588.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-fdb34588.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-fdb34588.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-fdb34588.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-fdb34588 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-fdb34588.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-fdb34588.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-3);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-fdb34588 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-fdb34588 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-fdb34588 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-fdb34588 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-fdb34588.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-fdb34588.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-fdb34588 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-fdb34588.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-fdb34588.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-fdb34588.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-fdb34588.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-block-3c078708 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3c078708 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3c078708 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3c078708 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3c078708 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3c078708{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3c078708 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 24px;}.wp-block-uagb-container.uagb-block-3c078708{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 24px;}.wp-block-uagb-container.uagb-block-694ce816 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-694ce816 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-694ce816 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-694ce816 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-694ce816 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-694ce816{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-694ce816 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 28px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-694ce816{box-shadow: 0px 0px   #00000070 ;padding-top: 32px;padding-bottom: 32px;padding-left: 32px;padding-right: 32px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: solid;border-color: var(--ast-global-color-6);background-color: var(--ast-global-color-5);;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 28px;column-gap: 0px;}.uagb-block-d49ddba8 .uagb-ifb-icon{width: 18px;line-height: 18px;}.uagb-block-d49ddba8 .uagb-ifb-icon > span{font-size: 18px;width: 18px;line-height: 18px;color: var(--ast-global-color-2);}.uagb-block-d49ddba8 .uagb-ifb-icon svg{fill: var(--ast-global-color-2);}.uagb-block-d49ddba8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 18px;height: 18px;line-height: 18px;font-size: 18px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-d49ddba8 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 18px;font-size: 18px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-d49ddba8 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 18px;height: 18px;line-height: 18px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-d49ddba8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-d49ddba8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-d49ddba8 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 18px;line-height: 18px;font-size: 18px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-d49ddba8 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 18px;line-height: 18px;font-size: 18px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-d49ddba8 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-d49ddba8 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-d49ddba8.uagb-infobox__content-wrap img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-d49ddba8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-d49ddba8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-d49ddba8.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-d49ddba8 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-d49ddba8.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 16px;margin-top: 20px;margin-left: 0px;margin-right: 0px;}.uagb-block-d49ddba8.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-3);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d49ddba8 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-d49ddba8 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-d49ddba8 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-d49ddba8 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-d49ddba8.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-d49ddba8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d49ddba8 .uagb-iconbox-icon-wrap.uagb-infobox-shape-circle{background-color: var(--ast-global-color-5);border-radius: 50%;}.uagb-block-d49ddba8 .uagb-iconbox-icon-wrap.uagb-infobox-shape-squre{background-color: var(--ast-global-color-5);}.uagb-block-d49ddba8 .uagb-iconbox-icon-wrap:hover{background-color:  !important;}.uagb-block-d49ddba8 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-d49ddba8.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-d49ddba8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-08292118.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 0px;}.uagb-block-08292118.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.wp-block-uagb-buttons .uagb-block-4fc7d6a2 .wp-block-button__link{background: transparent;}.wp-block-uagb-buttons .uagb-block-4fc7d6a2 .wp-block-button__link:hover{background: transparent;}.wp-block-uagb-buttons .uagb-block-4fc7d6a2 .wp-block-button__link:focus{background: transparent;}.wp-block-uagb-buttons .uagb-block-4fc7d6a2 .uagb-button__wrapper .uagb-buttons-repeater{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;color: var(--ast-global-color-2);margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-4fc7d6a2 .wp-block-button__link.has-text-color:hover .uagb-button__link{color: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-4fc7d6a2 .wp-block-button__link.has-text-color:focus .uagb-button__link{color: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-4fc7d6a2 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-4fc7d6a2 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-4fc7d6a2 .uagb-buttons-repeater .uagb-button__link{color: var(--ast-global-color-2);}.wp-block-uagb-buttons .uagb-block-4fc7d6a2 .uagb-buttons-repeater:hover .uagb-button__link{color: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-4fc7d6a2 .uagb-buttons-repeater:focus .uagb-button__link{color: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-4fc7d6a2 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: var(--ast-global-color-2);}.wp-block-uagb-buttons .uagb-block-4fc7d6a2 .uagb-buttons-repeater:hover .uagb-button__icon > svg{fill: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-4fc7d6a2 .uagb-buttons-repeater:focus .uagb-button__icon > svg{fill: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-4fc7d6a2 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-4fc7d6a2 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-4fc7d6a2 .uagb-button__link{text-transform: normal;text-decoration: none;}.wp-block-uagb-container.uagb-block-b558d6ab .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b558d6ab .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b558d6ab .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b558d6ab .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b558d6ab .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b558d6ab{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b558d6ab > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 28px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-b558d6ab{box-shadow: 0px 0px   #00000070 ;padding-top: 32px;padding-bottom: 32px;padding-left: 32px;padding-right: 32px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: solid;border-color: var(--ast-global-color-6);background-color: var(--ast-global-color-5);;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 28px;column-gap: 0px;}.uagb-block-ab9e8375 .uagb-ifb-icon{width: 18px;line-height: 18px;}.uagb-block-ab9e8375 .uagb-ifb-icon > span{font-size: 18px;width: 18px;line-height: 18px;color: var(--ast-global-color-2);}.uagb-block-ab9e8375 .uagb-ifb-icon svg{fill: var(--ast-global-color-2);}.uagb-block-ab9e8375.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 18px;height: 18px;line-height: 18px;font-size: 18px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-ab9e8375 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 18px;font-size: 18px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-ab9e8375 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 18px;height: 18px;line-height: 18px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-ab9e8375.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-ab9e8375.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-ab9e8375 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 18px;line-height: 18px;font-size: 18px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-ab9e8375 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 18px;line-height: 18px;font-size: 18px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-ab9e8375 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-ab9e8375 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-ab9e8375.uagb-infobox__content-wrap img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-ab9e8375.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-ab9e8375.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-ab9e8375.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-ab9e8375 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-ab9e8375.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 16px;margin-top: 20px;margin-left: 0px;margin-right: 0px;}.uagb-block-ab9e8375.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-3);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-ab9e8375 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-ab9e8375 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-ab9e8375 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-ab9e8375 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-ab9e8375.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-ab9e8375.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-ab9e8375 .uagb-iconbox-icon-wrap.uagb-infobox-shape-circle{background-color: var(--ast-global-color-5);border-radius: 50%;}.uagb-block-ab9e8375 .uagb-iconbox-icon-wrap.uagb-infobox-shape-squre{background-color: var(--ast-global-color-5);}.uagb-block-ab9e8375 .uagb-iconbox-icon-wrap:hover{background-color:  !important;}.uagb-block-ab9e8375 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-ab9e8375.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-ab9e8375.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-fdf46656.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 0px;}.uagb-block-fdf46656.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.wp-block-uagb-buttons .uagb-block-32051b39 .wp-block-button__link{background: transparent;}.wp-block-uagb-buttons .uagb-block-32051b39 .wp-block-button__link:hover{background: transparent;}.wp-block-uagb-buttons .uagb-block-32051b39 .wp-block-button__link:focus{background: transparent;}.wp-block-uagb-buttons .uagb-block-32051b39 .uagb-button__wrapper .uagb-buttons-repeater{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;color: var(--ast-global-color-2);margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-32051b39 .wp-block-button__link.has-text-color:hover .uagb-button__link{color: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-32051b39 .wp-block-button__link.has-text-color:focus .uagb-button__link{color: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-32051b39 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-32051b39 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-32051b39 .uagb-buttons-repeater .uagb-button__link{color: var(--ast-global-color-2);}.wp-block-uagb-buttons .uagb-block-32051b39 .uagb-buttons-repeater:hover .uagb-button__link{color: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-32051b39 .uagb-buttons-repeater:focus .uagb-button__link{color: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-32051b39 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: var(--ast-global-color-2);}.wp-block-uagb-buttons .uagb-block-32051b39 .uagb-buttons-repeater:hover .uagb-button__icon > svg{fill: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-32051b39 .uagb-buttons-repeater:focus .uagb-button__icon > svg{fill: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-32051b39 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-32051b39 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-32051b39 .uagb-button__link{text-transform: normal;text-decoration: none;}.wp-block-uagb-container.uagb-block-861d4591 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-861d4591 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-861d4591 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-861d4591 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-861d4591 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-861d4591{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-861d4591 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 28px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-861d4591{box-shadow: 0px 0px   #00000070 ;padding-top: 32px;padding-bottom: 32px;padding-left: 32px;padding-right: 32px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: solid;border-color: var(--ast-global-color-6);background-color: var(--ast-global-color-5);;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 28px;column-gap: 0px;}.uagb-block-2757b255 .uagb-ifb-icon{width: 18px;line-height: 18px;}.uagb-block-2757b255 .uagb-ifb-icon > span{font-size: 18px;width: 18px;line-height: 18px;color: var(--ast-global-color-2);}.uagb-block-2757b255 .uagb-ifb-icon svg{fill: var(--ast-global-color-2);}.uagb-block-2757b255.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 18px;height: 18px;line-height: 18px;font-size: 18px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-2757b255 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 18px;font-size: 18px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-2757b255 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 18px;height: 18px;line-height: 18px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-2757b255.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-2757b255.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-2757b255 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 18px;line-height: 18px;font-size: 18px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-2757b255 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 18px;line-height: 18px;font-size: 18px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-2757b255 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-2757b255 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-2757b255.uagb-infobox__content-wrap img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-2757b255.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-2757b255.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-2757b255.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-2757b255 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-2757b255.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 16px;margin-top: 20px;margin-left: 0px;margin-right: 0px;}.uagb-block-2757b255.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-3);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-2757b255 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-2757b255 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-2757b255 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-2757b255 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-2757b255.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-2757b255.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-2757b255 .uagb-iconbox-icon-wrap.uagb-infobox-shape-circle{background-color: var(--ast-global-color-5);border-radius: 50%;}.uagb-block-2757b255 .uagb-iconbox-icon-wrap.uagb-infobox-shape-squre{background-color: var(--ast-global-color-5);}.uagb-block-2757b255 .uagb-iconbox-icon-wrap:hover{background-color:  !important;}.uagb-block-2757b255 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-2757b255.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-2757b255.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-fd943482.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 0px;}.uagb-block-fd943482.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.wp-block-uagb-buttons .uagb-block-941fa188 .wp-block-button__link{background: transparent;}.wp-block-uagb-buttons .uagb-block-941fa188 .wp-block-button__link:hover{background: transparent;}.wp-block-uagb-buttons .uagb-block-941fa188 .wp-block-button__link:focus{background: transparent;}.wp-block-uagb-buttons .uagb-block-941fa188 .uagb-button__wrapper .uagb-buttons-repeater{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;color: var(--ast-global-color-2);margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-941fa188 .wp-block-button__link.has-text-color:hover .uagb-button__link{color: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-941fa188 .wp-block-button__link.has-text-color:focus .uagb-button__link{color: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-941fa188 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-941fa188 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-941fa188 .uagb-buttons-repeater .uagb-button__link{color: var(--ast-global-color-2);}.wp-block-uagb-buttons .uagb-block-941fa188 .uagb-buttons-repeater:hover .uagb-button__link{color: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-941fa188 .uagb-buttons-repeater:focus .uagb-button__link{color: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-941fa188 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: var(--ast-global-color-2);}.wp-block-uagb-buttons .uagb-block-941fa188 .uagb-buttons-repeater:hover .uagb-button__icon > svg{fill: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-941fa188 .uagb-buttons-repeater:focus .uagb-button__icon > svg{fill: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-941fa188 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-941fa188 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-941fa188 .uagb-button__link{text-transform: normal;text-decoration: none;}.wp-block-uagb-container.uagb-block-dd28d95c .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-dd28d95c .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-dd28d95c .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-dd28d95c .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-dd28d95c .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-dd28d95c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dd28d95c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: flex-start;flex-wrap: wrap;align-content: flex-start;row-gap: 72px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-dd28d95c{box-shadow: 0px 0px   #00000070 ;padding-top: 112px;padding-bottom: 112px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-5);;row-gap: 72px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-609fec64 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-609fec64 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-609fec64 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-609fec64 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-609fec64 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-609fec64{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-609fec64 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 72px;}.wp-block-uagb-container.uagb-block-609fec64{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: stretch;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 72px;}.wp-block-uagb-container.uagb-block-72f13e20 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-72f13e20 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-72f13e20 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-72f13e20 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-72f13e20 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-72f13e20{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-72f13e20 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-72f13e20{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-1882db2b .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-1882db2b .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-1882db2b .uagb-ifb-icon svg{fill: #333;}.uagb-block-1882db2b.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-1882db2b .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-1882db2b .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-1882db2b.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-1882db2b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-1882db2b .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-1882db2b .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-1882db2b .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-1882db2b .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-1882db2b.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-1882db2b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-1882db2b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-1882db2b.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-1882db2b .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-1882db2b.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-1882db2b.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-1882db2b .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-1882db2b .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-1882db2b .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-1882db2b .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-1882db2b.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-1882db2b.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-1882db2b .uagb-infobox__content-wrap{text-align: left;}.uagb-block-1882db2b.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-1882db2b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-block-4a8d035b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4a8d035b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4a8d035b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4a8d035b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4a8d035b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4a8d035b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4a8d035b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-4a8d035b{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-3a19b4ea .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-3a19b4ea .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-3a19b4ea .uagb-ifb-icon svg{fill: #333;}.uagb-block-3a19b4ea.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3a19b4ea .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3a19b4ea .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3a19b4ea.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3a19b4ea.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3a19b4ea .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3a19b4ea .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3a19b4ea .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3a19b4ea .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-3a19b4ea.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3a19b4ea.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3a19b4ea.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3a19b4ea.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3a19b4ea .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-3a19b4ea.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-3);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-3a19b4ea.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-3a19b4ea .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-3a19b4ea .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-3a19b4ea .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-3a19b4ea .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-3a19b4ea.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-3a19b4ea.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-3a19b4ea .uagb-infobox__content-wrap{text-align: left;}.uagb-block-3a19b4ea.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-3a19b4ea.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-block-8f6c422d .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8f6c422d .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8f6c422d .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8f6c422d .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8f6c422d .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8f6c422d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8f6c422d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 72px;}.wp-block-uagb-container.uagb-block-8f6c422d{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: stretch;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 72px;}.wp-block-uagb-container.uagb-block-0ba6d01d .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0ba6d01d .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0ba6d01d .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0ba6d01d .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0ba6d01d .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0ba6d01d{max-width: 35%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0ba6d01d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-0ba6d01d{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-4e75022d.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-4e75022d .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-4e75022d.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-4e75022d.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-4e75022d.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-4e75022d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-4e75022d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-4e75022d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-4e75022d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-4e75022d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-4e75022d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-4e75022d.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-4e75022d.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 600px;height: 500px;}.uagb-block-4e75022d.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-4e75022d.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-4e75022d.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-4e75022d.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-56e1cd58 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-56e1cd58 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-56e1cd58 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-56e1cd58 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-56e1cd58 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-56e1cd58{max-width: 65%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-56e1cd58 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-56e1cd58{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-f2a241b1 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f2a241b1 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f2a241b1 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f2a241b1 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f2a241b1 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f2a241b1{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f2a241b1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 48px;}.wp-block-uagb-container.uagb-block-f2a241b1{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 48px;padding-left: 10px;padding-right: 10px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-top-width: 0px;border-left-width: 0px;border-right-width: 0px;border-bottom-width: 1px;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-style: solid;border-color: var(--ast-global-color-6);flex-direction: row;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 48px;}.wp-block-uagb-container.wp-block-uagb-container.uagb-block-f2a241b1:hover{border-color: var(--ast-global-color-6);}.uagb-block-c5554396 .uagb-ifb-icon{width: 20px;line-height: 20px;}.uagb-block-c5554396 .uagb-ifb-icon > span{font-size: 20px;width: 20px;line-height: 20px;color: var(--ast-global-color-2);}.uagb-block-c5554396 .uagb-ifb-icon svg{fill: var(--ast-global-color-2);}.uagb-block-c5554396.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-c5554396 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-c5554396 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 20px;height: 20px;line-height: 20px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-c5554396.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-c5554396.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-c5554396 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 20px;line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-c5554396 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 20px;line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-c5554396 .uagb-ifb-content .uagb-ifb-icon-wrap svg:hover{fill: var(--ast-global-color-2);color: var(--ast-global-color-2);}.uagb-block-c5554396.uagb-infobox-icon-right .uagb-ifb-icon-wrap > svg:hover{fill: var(--ast-global-color-2);color: var(--ast-global-color-2);}.uagb-block-c5554396.uagb-infobox-icon-left .uagb-ifb-icon-wrap > svg:hover{fill: var(--ast-global-color-2);color: var(--ast-global-color-2);}.uagb-block-c5554396 .uagb-infbox__link-to-all:hover ~.uagb-ifb-content .uagb-ifb-icon-wrap svg{fill: var(--ast-global-color-2);}.uagb-block-c5554396.uagb-infbox__link-to-all:hover ~.uagb-infobox__content-wrap svg{fill: var(--ast-global-color-2);}.uagb-block-c5554396 .uagb-infbox__link-to-all:focus ~.uagb-ifb-content .uagb-ifb-icon-wrap svg{fill: var(--ast-global-color-2);}.uagb-block-c5554396.uagb-infbox__link-to-all:focus ~.uagb-infobox__content-wrap svg{fill: var(--ast-global-color-2);}.uagb-block-c5554396 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-c5554396 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-c5554396.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;border-radius: 0px;}.uagb-block-c5554396.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;border-radius: 0px;}.uagb-block-c5554396.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;border-radius: 0px;}.uagb-block-c5554396.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;border-radius: 0px;}.uagb-block-c5554396 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-c5554396.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 16px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-c5554396.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-3);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-c5554396 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-c5554396 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-c5554396 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-c5554396 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-c5554396.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-c5554396.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-c5554396 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-c5554396.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-c5554396.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-c5554396.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-c5554396.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-b685501a .uagb-ifb-icon{width: 20px;line-height: 20px;}.uagb-block-b685501a .uagb-ifb-icon > span{font-size: 20px;width: 20px;line-height: 20px;color: var(--ast-global-color-2);}.uagb-block-b685501a .uagb-ifb-icon svg{fill: var(--ast-global-color-2);}.uagb-block-b685501a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-b685501a .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-b685501a .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 20px;height: 20px;line-height: 20px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-b685501a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-b685501a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-b685501a .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 20px;line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-b685501a .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 20px;line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-b685501a .uagb-ifb-content .uagb-ifb-icon-wrap svg:hover{fill: var(--ast-global-color-2);color: var(--ast-global-color-2);}.uagb-block-b685501a.uagb-infobox-icon-right .uagb-ifb-icon-wrap > svg:hover{fill: var(--ast-global-color-2);color: var(--ast-global-color-2);}.uagb-block-b685501a.uagb-infobox-icon-left .uagb-ifb-icon-wrap > svg:hover{fill: var(--ast-global-color-2);color: var(--ast-global-color-2);}.uagb-block-b685501a .uagb-infbox__link-to-all:hover ~.uagb-ifb-content .uagb-ifb-icon-wrap svg{fill: var(--ast-global-color-2);}.uagb-block-b685501a.uagb-infbox__link-to-all:hover ~.uagb-infobox__content-wrap svg{fill: var(--ast-global-color-2);}.uagb-block-b685501a .uagb-infbox__link-to-all:focus ~.uagb-ifb-content .uagb-ifb-icon-wrap svg{fill: var(--ast-global-color-2);}.uagb-block-b685501a.uagb-infbox__link-to-all:focus ~.uagb-infobox__content-wrap svg{fill: var(--ast-global-color-2);}.uagb-block-b685501a .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-b685501a .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-b685501a.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;border-radius: 0px;}.uagb-block-b685501a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;border-radius: 0px;}.uagb-block-b685501a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;border-radius: 0px;}.uagb-block-b685501a.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;border-radius: 0px;}.uagb-block-b685501a .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-b685501a.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 16px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-b685501a.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-3);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-b685501a .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-b685501a .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-b685501a .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-b685501a .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-b685501a.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-b685501a.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b685501a .uagb-infobox__content-wrap{text-align: left;}.uagb-block-b685501a.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-b685501a.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-b685501a.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-b685501a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-block-737a9fe3 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-737a9fe3 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-737a9fe3 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-737a9fe3 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-737a9fe3 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-737a9fe3{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-737a9fe3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 48px;}.wp-block-uagb-container.uagb-block-737a9fe3{box-shadow: 0px 0px   #00000070 ;padding-top: 24px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 48px;}.uagb-block-b31d2911 .uagb-ifb-icon{width: 20px;line-height: 20px;}.uagb-block-b31d2911 .uagb-ifb-icon > span{font-size: 20px;width: 20px;line-height: 20px;color: var(--ast-global-color-2);}.uagb-block-b31d2911 .uagb-ifb-icon svg{fill: var(--ast-global-color-2);}.uagb-block-b31d2911.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-b31d2911 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-b31d2911 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 20px;height: 20px;line-height: 20px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-b31d2911.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-b31d2911.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-b31d2911 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 20px;line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-b31d2911 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 20px;line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-b31d2911 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-b31d2911 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-b31d2911.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;border-radius: 0px;}.uagb-block-b31d2911.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;border-radius: 0px;}.uagb-block-b31d2911.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;border-radius: 0px;}.uagb-block-b31d2911.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;border-radius: 0px;}.uagb-block-b31d2911 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-b31d2911.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 16px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-b31d2911.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-3);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-b31d2911 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-b31d2911 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-b31d2911 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-b31d2911 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-b31d2911.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-b31d2911.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b31d2911 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-b31d2911.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-b31d2911.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-b31d2911.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-b31d2911.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-75008db2 .uagb-ifb-icon{width: 20px;line-height: 20px;}.uagb-block-75008db2 .uagb-ifb-icon > span{font-size: 20px;width: 20px;line-height: 20px;color: var(--ast-global-color-2);}.uagb-block-75008db2 .uagb-ifb-icon svg{fill: var(--ast-global-color-2);}.uagb-block-75008db2.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-75008db2 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-75008db2 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 20px;height: 20px;line-height: 20px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-75008db2.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-75008db2.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-75008db2 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 20px;line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-75008db2 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 20px;line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-75008db2 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;}.uagb-block-75008db2 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-75008db2.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;border-radius: 0px;}.uagb-block-75008db2.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;border-radius: 0px;}.uagb-block-75008db2.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;border-radius: 0px;}.uagb-block-75008db2.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 20px;border-radius: 0px;}.uagb-block-75008db2 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-75008db2.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 16px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-75008db2.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-3);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-75008db2 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-75008db2 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-75008db2 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-75008db2 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-75008db2.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-75008db2.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-75008db2 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-75008db2.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-75008db2.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-75008db2.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-75008db2.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-block-0875eb55 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0875eb55 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0875eb55 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0875eb55 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0875eb55 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0875eb55{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0875eb55 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 40px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-0875eb55{box-shadow: 0px 0px   #00000070 ;padding-top: 112px;padding-bottom: 112px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-5);;row-gap: 40px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-abcd4e61 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-abcd4e61 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-abcd4e61 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-abcd4e61 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-abcd4e61 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-abcd4e61{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-abcd4e61 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-abcd4e61{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-47b7c002 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-47b7c002 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-47b7c002 .uagb-ifb-icon svg{fill: #333;}.uagb-block-47b7c002.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-47b7c002 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-47b7c002 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-47b7c002.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-47b7c002.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-47b7c002 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-47b7c002 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-47b7c002 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-47b7c002 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-47b7c002.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-47b7c002.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-47b7c002.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-47b7c002.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-47b7c002 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-47b7c002.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-47b7c002.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-3);margin-bottom: 0%;margin-top: 0%;margin-left: 15%;margin-right: 15%;}.uagb-block-47b7c002 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-47b7c002 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-47b7c002 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-47b7c002 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-47b7c002.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-47b7c002.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-47b7c002 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-47b7c002.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-47b7c002.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-47b7c002.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-47b7c002.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-block-f837bf6f .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f837bf6f .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f837bf6f .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f837bf6f .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f837bf6f .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f837bf6f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f837bf6f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 48px;}.wp-block-uagb-container.uagb-block-f837bf6f{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 48px;}.wp-block-uagb-container.uagb-block-27788532 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-27788532 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-27788532 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-27788532 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-27788532 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-27788532{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-27788532 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-27788532{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-ead7767b .uagb-ifb-icon{width: 20px;line-height: 20px;}.uagb-block-ead7767b .uagb-ifb-icon > span{font-size: 20px;width: 20px;line-height: 20px;color: var(--ast-global-color-2);}.uagb-block-ead7767b .uagb-ifb-icon svg{fill: var(--ast-global-color-2);}.uagb-block-ead7767b.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-ead7767b .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-ead7767b .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 20px;height: 20px;line-height: 20px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-ead7767b.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-ead7767b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-ead7767b .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 20px;line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-ead7767b .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 20px;line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-ead7767b .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-ead7767b .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-ead7767b.uagb-infobox__content-wrap img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-ead7767b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-ead7767b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-ead7767b.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-ead7767b .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-ead7767b.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 16px;margin-top: 20px;margin-left: 0px;margin-right: 0px;}.uagb-block-ead7767b.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-3);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-ead7767b .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-ead7767b .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-ead7767b .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-ead7767b .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-ead7767b.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-ead7767b.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-ead7767b .uagb-iconbox-icon-wrap.uagb-infobox-shape-circle{background-color: var(--ast-global-color-5);border-radius: 50%;}.uagb-block-ead7767b .uagb-iconbox-icon-wrap.uagb-infobox-shape-squre{background-color: var(--ast-global-color-5);}.uagb-block-ead7767b .uagb-iconbox-icon-wrap:hover{background-color:  !important;}.uagb-block-ead7767b .uagb-infobox__content-wrap{text-align: center;}.uagb-block-ead7767b.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-ead7767b.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-ead7767b.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-ead7767b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-block-200adade .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-200adade .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-200adade .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-200adade .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-200adade .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-200adade{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-200adade > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-200adade{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-14c90ca5 .uagb-ifb-icon{width: 20px;line-height: 20px;}.uagb-block-14c90ca5 .uagb-ifb-icon > span{font-size: 20px;width: 20px;line-height: 20px;color: var(--ast-global-color-2);}.uagb-block-14c90ca5 .uagb-ifb-icon svg{fill: var(--ast-global-color-2);}.uagb-block-14c90ca5.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-14c90ca5 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-14c90ca5 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 20px;height: 20px;line-height: 20px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-14c90ca5.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-14c90ca5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-14c90ca5 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 20px;line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-14c90ca5 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 20px;line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-14c90ca5 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-14c90ca5 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-14c90ca5.uagb-infobox__content-wrap img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-14c90ca5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-14c90ca5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-14c90ca5.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-14c90ca5 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-14c90ca5.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 16px;margin-top: 20px;margin-left: 0px;margin-right: 0px;}.uagb-block-14c90ca5.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-3);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-14c90ca5 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-14c90ca5 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-14c90ca5 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-14c90ca5 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-14c90ca5.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-14c90ca5.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-14c90ca5 .uagb-iconbox-icon-wrap.uagb-infobox-shape-circle{background-color: var(--ast-global-color-5);border-radius: 50%;}.uagb-block-14c90ca5 .uagb-iconbox-icon-wrap.uagb-infobox-shape-squre{background-color: var(--ast-global-color-5);}.uagb-block-14c90ca5 .uagb-iconbox-icon-wrap:hover{background-color:  !important;}.uagb-block-14c90ca5 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-14c90ca5.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-14c90ca5.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-14c90ca5.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-14c90ca5.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-block-fd033695 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-fd033695 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-fd033695 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-fd033695 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-fd033695 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-fd033695{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fd033695 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-fd033695{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-caa994d6 .uagb-ifb-icon{width: 20px;line-height: 20px;}.uagb-block-caa994d6 .uagb-ifb-icon > span{font-size: 20px;width: 20px;line-height: 20px;color: var(--ast-global-color-2);}.uagb-block-caa994d6 .uagb-ifb-icon svg{fill: var(--ast-global-color-2);}.uagb-block-caa994d6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-caa994d6 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-caa994d6 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 20px;height: 20px;line-height: 20px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-caa994d6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-caa994d6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-caa994d6 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 20px;line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-caa994d6 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 20px;line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-caa994d6 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-caa994d6 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-caa994d6.uagb-infobox__content-wrap img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-caa994d6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-caa994d6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-caa994d6.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;border-radius: 0px;}.uagb-block-caa994d6 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-caa994d6.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 16px;margin-top: 20px;margin-left: 0px;margin-right: 0px;}.uagb-block-caa994d6.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-3);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-caa994d6 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-caa994d6 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-caa994d6 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-caa994d6 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-caa994d6.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-caa994d6.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-caa994d6 .uagb-iconbox-icon-wrap.uagb-infobox-shape-circle{background-color: var(--ast-global-color-5);border-radius: 50%;}.uagb-block-caa994d6 .uagb-iconbox-icon-wrap.uagb-infobox-shape-squre{background-color: var(--ast-global-color-5);}.uagb-block-caa994d6 .uagb-iconbox-icon-wrap:hover{background-color:  !important;}.uagb-block-caa994d6 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-caa994d6.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-caa994d6.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-caa994d6.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-caa994d6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-block-e8a2a613 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e8a2a613 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e8a2a613 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e8a2a613 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e8a2a613 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e8a2a613{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e8a2a613 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 60px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-e8a2a613{box-shadow: 0px 0px   #00000070 ;padding-top: 112px;padding-bottom: 112px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-5);;row-gap: 60px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-51e2c002 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-51e2c002 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-51e2c002 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-51e2c002 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-51e2c002 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-51e2c002{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-51e2c002 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-51e2c002{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-fc90a4a2 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-fc90a4a2 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-fc90a4a2 .uagb-ifb-icon svg{fill: #333;}.uagb-block-fc90a4a2.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-fc90a4a2 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-fc90a4a2 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fc90a4a2.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fc90a4a2.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fc90a4a2 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-fc90a4a2 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-fc90a4a2 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-fc90a4a2 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-fc90a4a2.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-fc90a4a2.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-fc90a4a2.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-fc90a4a2.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-fc90a4a2 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-fc90a4a2.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-fc90a4a2.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-3);margin-bottom: 0%;margin-top: 0%;margin-left: 15%;margin-right: 15%;}.uagb-block-fc90a4a2 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-fc90a4a2 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-fc90a4a2 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-fc90a4a2 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-fc90a4a2.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-fc90a4a2.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-fc90a4a2 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-fc90a4a2.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-fc90a4a2.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-fc90a4a2.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-fc90a4a2.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-block-f2f686c0 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f2f686c0 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f2f686c0 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f2f686c0 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f2f686c0 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f2f686c0{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f2f686c0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-f2f686c0{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-03da51f9 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-03da51f9 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-03da51f9 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-03da51f9 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-03da51f9 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-03da51f9{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-03da51f9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 24px;}.wp-block-uagb-container.uagb-block-03da51f9{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 24px;}.wp-block-uagb-container.uagb-block-bca0ac81 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-bca0ac81 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-bca0ac81 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-bca0ac81 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-bca0ac81 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bca0ac81{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bca0ac81 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 24px;}.wp-block-uagb-container.uagb-block-bca0ac81{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 24px;}.uagb-block-e4fcfe5f.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-e4fcfe5f.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-e4fcfe5f.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-e4fcfe5f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-e4fcfe5f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-e4fcfe5f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-e4fcfe5f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-e4fcfe5f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-e4fcfe5f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-e4fcfe5f.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-e4fcfe5f.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 282px;height: 282px;}.uagb-block-e4fcfe5f.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-e4fcfe5f.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-e4fcfe5f.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-e4fcfe5f.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-0a7ee55f.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-0a7ee55f.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-0a7ee55f.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-0a7ee55f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-0a7ee55f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-0a7ee55f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-0a7ee55f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-0a7ee55f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-0a7ee55f.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-0a7ee55f.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-0a7ee55f.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 282px;height: 282px;}.uagb-block-0a7ee55f.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-0a7ee55f.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-0a7ee55f.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-0a7ee55f.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-42ebd4f6 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-42ebd4f6 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-42ebd4f6 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-42ebd4f6 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-42ebd4f6 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-42ebd4f6{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-42ebd4f6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 24px;}.wp-block-uagb-container.uagb-block-42ebd4f6{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 24px;}.uagb-block-4a7f1049.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-4a7f1049.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-4a7f1049.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-4a7f1049.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-4a7f1049.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-4a7f1049.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-4a7f1049.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-4a7f1049.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-4a7f1049.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-4a7f1049.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-4a7f1049.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 282px;height: 282px;}.uagb-block-4a7f1049.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-4a7f1049.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-4a7f1049.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-4a7f1049.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-271d56c7.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-271d56c7.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-271d56c7.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-271d56c7.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-271d56c7.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-271d56c7.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-271d56c7.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-271d56c7.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-271d56c7.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-271d56c7.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-271d56c7.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 282px;height: 282px;}.uagb-block-271d56c7.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-271d56c7.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-271d56c7.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-271d56c7.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-3560d1a5 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3560d1a5 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3560d1a5 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3560d1a5 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3560d1a5 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3560d1a5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3560d1a5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 24px;}.wp-block-uagb-container.uagb-block-3560d1a5{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 24px;}.wp-block-uagb-container.uagb-block-5894fa70 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5894fa70 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5894fa70 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5894fa70 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5894fa70 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5894fa70{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5894fa70 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5894fa70{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-6770cd95.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-6770cd95.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-6770cd95.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-6770cd95.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-6770cd95.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-6770cd95.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-6770cd95.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-6770cd95.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-6770cd95.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-6770cd95.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-6770cd95.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 282px;height: 282px;}.uagb-block-6770cd95.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-6770cd95.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-6770cd95.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-6770cd95.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-b201bcee.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-b201bcee.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-b201bcee.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-b201bcee.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-b201bcee.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-b201bcee.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-b201bcee.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-b201bcee.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-b201bcee.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-b201bcee.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-b201bcee.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 282px;height: 282px;}.uagb-block-b201bcee.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-b201bcee.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-b201bcee.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-b201bcee.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-0a3f9b21 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0a3f9b21 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0a3f9b21 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0a3f9b21 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0a3f9b21 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0a3f9b21{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0a3f9b21 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-0a3f9b21{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-728c8074.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-728c8074.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-728c8074.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-728c8074.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-728c8074.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-728c8074.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-728c8074.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-728c8074.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-728c8074.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-728c8074.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-728c8074.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 282px;height: 282px;}.uagb-block-728c8074.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-728c8074.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-728c8074.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-728c8074.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-9206fcbd.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-9206fcbd.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-9206fcbd.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-9206fcbd.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-9206fcbd.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-9206fcbd.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-9206fcbd.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-9206fcbd.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-9206fcbd.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-9206fcbd.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-9206fcbd.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 282px;height: 282px;}.uagb-block-9206fcbd.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-9206fcbd.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-9206fcbd.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-9206fcbd.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-7904eaf3 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7904eaf3 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7904eaf3 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7904eaf3 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7904eaf3 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7904eaf3{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7904eaf3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 64px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-7904eaf3{box-shadow: 0px 0px   #00000070 ;padding-top: 112px;padding-bottom: 112px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-5);;row-gap: 64px;column-gap: 0px;}.uagb-block-18e6815d .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-18e6815d .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-18e6815d .uagb-ifb-icon svg{fill: #333;}.uagb-block-18e6815d.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-18e6815d .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-18e6815d .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-18e6815d.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-18e6815d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-18e6815d .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-18e6815d .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-18e6815d .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-18e6815d .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-18e6815d.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-18e6815d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-18e6815d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-18e6815d.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-18e6815d .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-18e6815d.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-18e6815d.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-3);margin-bottom: 0%;margin-top: 0%;margin-left: 15%;margin-right: 15%;}.uagb-block-18e6815d .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-18e6815d .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-18e6815d .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-18e6815d .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-18e6815d.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-18e6815d.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-18e6815d .uagb-infobox__content-wrap{text-align: center;}.uagb-block-18e6815d.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-18e6815d.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-18e6815d.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-18e6815d.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-block-ec11566e .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ec11566e .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ec11566e .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-ec11566e .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-ec11566e .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ec11566e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ec11566e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-ec11566e{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-08bf843c .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-08bf843c .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-08bf843c .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-08bf843c .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-08bf843c .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-08bf843c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-08bf843c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 24px;}.wp-block-uagb-container.uagb-block-08bf843c{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: stretch;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 24px;}.wp-block-uagb-container.uagb-block-920cad8c .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-920cad8c .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-920cad8c .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-920cad8c .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-920cad8c .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-920cad8c{max-width: 68%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-920cad8c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-920cad8c{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-5bb0bbc0.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-5bb0bbc0 .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-5bb0bbc0.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-5bb0bbc0.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-5bb0bbc0.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-5bb0bbc0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-5bb0bbc0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-5bb0bbc0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-5bb0bbc0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-5bb0bbc0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-5bb0bbc0.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-5bb0bbc0.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-5bb0bbc0.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 792px;height: 446px;}.uagb-block-5bb0bbc0.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-5bb0bbc0.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-5bb0bbc0.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5bb0bbc0.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-e0323075 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e0323075 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e0323075 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e0323075 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e0323075 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e0323075{max-width: 32%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e0323075 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-e0323075{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-9cbc911a.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-9cbc911a .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-9cbc911a.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-9cbc911a.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-9cbc911a.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-9cbc911a.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-9cbc911a.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-9cbc911a.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-9cbc911a.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-9cbc911a.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-9cbc911a.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-9cbc911a.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-9cbc911a.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 400px;height: 446px;}.uagb-block-9cbc911a.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-9cbc911a.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-9cbc911a.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-9cbc911a.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-01bd5354 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-01bd5354 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-01bd5354 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-01bd5354 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-01bd5354 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-01bd5354{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-01bd5354 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 24px;}.wp-block-uagb-container.uagb-block-01bd5354{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: stretch;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 24px;}.wp-block-uagb-container.uagb-block-aa24ab14 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-aa24ab14 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-aa24ab14 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-aa24ab14 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-aa24ab14 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-aa24ab14{max-width: 32%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-aa24ab14 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-aa24ab14{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-df48cc3c.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-df48cc3c .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-df48cc3c.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-df48cc3c.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-df48cc3c.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-df48cc3c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-df48cc3c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-df48cc3c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-df48cc3c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-df48cc3c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-df48cc3c.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-df48cc3c.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-df48cc3c.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 400px;height: 466px;}.uagb-block-df48cc3c.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-df48cc3c.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-df48cc3c.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-df48cc3c.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-c6438229 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c6438229 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c6438229 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c6438229 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c6438229 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c6438229{max-width: 68%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c6438229 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-c6438229{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-34281fbc.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-34281fbc .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-34281fbc.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-34281fbc.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-34281fbc.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-34281fbc.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-34281fbc.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-34281fbc.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-34281fbc.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-34281fbc.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-34281fbc.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-34281fbc.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-34281fbc.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 792px;height: 466px;}.uagb-block-34281fbc.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-34281fbc.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-34281fbc.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-34281fbc.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-a37cb94d .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a37cb94d .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a37cb94d .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a37cb94d .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a37cb94d .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a37cb94d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a37cb94d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 72px;}.wp-block-uagb-container.uagb-block-a37cb94d{box-shadow: 0px 0px   #00000070 ;padding-top: 112px;padding-bottom: 112px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-5);;row-gap: 0px;column-gap: 72px;}.wp-block-uagb-container.uagb-block-02b2643c .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-02b2643c .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-02b2643c .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-02b2643c .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-02b2643c .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-02b2643c{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-02b2643c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 48px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-02b2643c{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 48px;column-gap: 0px;}.uagb-block-cf9e68d1 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-cf9e68d1 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-cf9e68d1 .uagb-ifb-icon svg{fill: #333;}.uagb-block-cf9e68d1.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-cf9e68d1 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-cf9e68d1 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-cf9e68d1.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-cf9e68d1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-cf9e68d1 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-cf9e68d1 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-cf9e68d1 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-cf9e68d1 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-cf9e68d1.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-cf9e68d1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-cf9e68d1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-cf9e68d1.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-cf9e68d1 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{color: var(--ast-global-color-2);margin-bottom: 24px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-cf9e68d1.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-cf9e68d1.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-3);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-cf9e68d1 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-cf9e68d1 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-cf9e68d1 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-cf9e68d1 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-cf9e68d1.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-cf9e68d1.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-cf9e68d1 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-cf9e68d1.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-cf9e68d1.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-cf9e68d1.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-cf9e68d1.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-block-0db1fe01 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0db1fe01 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0db1fe01 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0db1fe01 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0db1fe01 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0db1fe01{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0db1fe01 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-0db1fe01{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;}.uagb-block-c5887fb5 .uagb-ifb-icon{width: 20px;line-height: 20px;}.uagb-block-c5887fb5 .uagb-ifb-icon > span{font-size: 20px;width: 20px;line-height: 20px;color: var(--ast-global-color-2);}.uagb-block-c5887fb5 .uagb-ifb-icon svg{fill: var(--ast-global-color-2);}.uagb-block-c5887fb5.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-c5887fb5 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-c5887fb5 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 20px;height: 20px;line-height: 20px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c5887fb5.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c5887fb5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c5887fb5 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 20px;line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-c5887fb5 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 20px;line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-c5887fb5 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c5887fb5 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-c5887fb5.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-c5887fb5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-c5887fb5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-c5887fb5.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-c5887fb5 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-c5887fb5.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 8px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-c5887fb5.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-3);margin-bottom: 3px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-c5887fb5 .uagb-ifb-separator{width: 100%;border-top-width: 1px;border-top-color: var(--ast-global-color-6);border-top-style: solid;margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-c5887fb5 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 100%;border-top-width: 1px;border-top-color: var(--ast-global-color-6);border-top-style: solid;}.uagb-block-c5887fb5 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-c5887fb5 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-c5887fb5.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-c5887fb5.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-c5887fb5.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-8320b8f4 .uagb-ifb-icon{width: 20px;line-height: 20px;}.uagb-block-8320b8f4 .uagb-ifb-icon > span{font-size: 20px;width: 20px;line-height: 20px;color: var(--ast-global-color-2);}.uagb-block-8320b8f4 .uagb-ifb-icon svg{fill: var(--ast-global-color-2);}.uagb-block-8320b8f4.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-8320b8f4 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-8320b8f4 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 20px;height: 20px;line-height: 20px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-8320b8f4.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-8320b8f4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-8320b8f4 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 20px;line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-8320b8f4 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 20px;line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-8320b8f4 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-8320b8f4 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-8320b8f4.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-8320b8f4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-8320b8f4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-8320b8f4.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-8320b8f4 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-8320b8f4.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 8px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-8320b8f4.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-3);margin-bottom: 3px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-8320b8f4 .uagb-ifb-separator{width: 100%;border-top-width: 1px;border-top-color: var(--ast-global-color-6);border-top-style: solid;margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-8320b8f4 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 100%;border-top-width: 1px;border-top-color: var(--ast-global-color-6);border-top-style: solid;}.uagb-block-8320b8f4 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-8320b8f4 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-8320b8f4.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-8320b8f4.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-8320b8f4.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-26acf763 .uagb-ifb-icon{width: 20px;line-height: 20px;}.uagb-block-26acf763 .uagb-ifb-icon > span{font-size: 20px;width: 20px;line-height: 20px;color: var(--ast-global-color-2);}.uagb-block-26acf763 .uagb-ifb-icon svg{fill: var(--ast-global-color-2);}.uagb-block-26acf763.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-26acf763 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-26acf763 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 20px;height: 20px;line-height: 20px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-26acf763.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-26acf763.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-26acf763 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 20px;line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-26acf763 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 20px;line-height: 20px;font-size: 20px;color: var(--ast-global-color-2);fill: var(--ast-global-color-2);}.uagb-block-26acf763 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-26acf763 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-26acf763.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-26acf763.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-26acf763.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-26acf763.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-26acf763 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-26acf763.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-2);margin-bottom: 8px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-26acf763.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-3);margin-bottom: 3px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-26acf763 .uagb-ifb-separator{width: 100%;border-top-width: 1px;border-top-color: var(--ast-global-color-6);border-top-style: solid;margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-26acf763 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 100%;border-top-width: 1px;border-top-color: var(--ast-global-color-6);border-top-style: solid;}.uagb-block-26acf763 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-26acf763 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-26acf763.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-26acf763.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-26acf763.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-block-25055c6b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-25055c6b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-25055c6b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-25055c6b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-25055c6b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-25055c6b{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-25055c6b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-25055c6b{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-2b404dfd.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-2b404dfd .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-2b404dfd.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-2b404dfd.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-2b404dfd.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-2b404dfd.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;}.uagb-block-2b404dfd.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-2b404dfd.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-2b404dfd.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-2b404dfd.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-2b404dfd.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-2b404dfd.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-2b404dfd.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 564px;height: 500px;}.uagb-block-2b404dfd.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-2b404dfd.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-2b404dfd.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-2b404dfd.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-container.uagb-block-45f809f9 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-45f809f9 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-45f809f9 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-45f809f9 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-45f809f9 .uagb-container__video-wrap video{opacity: 0.3;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-45f809f9{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-45f809f9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 80px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-45f809f9{box-shadow: 0px 0px   #00000070 ;padding-top: 112px;padding-bottom: 112px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/10\/natures-01.jpg);;background-clip: padding-box;row-gap: 80px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-45f809f9::before{content: \"\";position: absolute;pointer-events: none;top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);border-color: inherit;background: var(--ast-global-color-7);opacity: 0.7;}.uagb-block-25ee98b8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-25ee98b8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-25ee98b8 .uagb-ifb-icon svg{fill: #333;}.uagb-block-25ee98b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-25ee98b8 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-25ee98b8 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-25ee98b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-25ee98b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-25ee98b8 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-25ee98b8 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-25ee98b8 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-25ee98b8 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-25ee98b8.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-25ee98b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-25ee98b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-25ee98b8.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-25ee98b8 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{color: #ffffff;margin-bottom: 16px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-25ee98b8.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 24px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-25ee98b8.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0%;margin-top: 0%;margin-left: 15%;margin-right: 15%;}.uagb-block-25ee98b8 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-25ee98b8 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-25ee98b8 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-25ee98b8 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-25ee98b8.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-25ee98b8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-25ee98b8 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-25ee98b8.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-25ee98b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-block-f9770f2e .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f9770f2e .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f9770f2e .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f9770f2e .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f9770f2e .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f9770f2e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f9770f2e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 48px;}.wp-block-uagb-container.uagb-block-f9770f2e{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 48px;}.wp-block-uagb-container.uagb-block-a49f2642 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a49f2642 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a49f2642 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a49f2642 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a49f2642 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a49f2642{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a49f2642 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-a49f2642{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;} .uagb-block-9d745acf .uag-star-rating{font-size: 20px;} .uagb-block-9d745acf .uag-star-rating > span{margin-right: 2px;color: #ccd6df;} .uagb-block-9d745acf .uag-star:nth-child(-n+5){color: #f0ad4e;} .uagb-block-9d745acf .uag-star-rating__title{margin-right: 10px;} .uagb-block-9d745acf.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;} .uagb-block-9d745acf .uag-star:nth-child(5):before{color: #f0ad4e;width: 0%;position: absolute;content: '\u2605';overflow: hidden;} .uagb-block-9d745acf .uag-star:nth-child(5){position: relative;}.uagb-block-5f444e21 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-5f444e21 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-5f444e21 .uagb-ifb-icon svg{fill: #333;}.uagb-block-5f444e21.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-5f444e21 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-5f444e21 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-5f444e21.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-5f444e21.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-5f444e21 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-5f444e21 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-5f444e21 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-5f444e21 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-5f444e21.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-5f444e21.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-5f444e21.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-5f444e21.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-5f444e21 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-5f444e21.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-5);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-5f444e21.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-5f444e21 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-5f444e21 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-5f444e21 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-5f444e21 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-5f444e21.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-5f444e21.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-5f444e21 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-5f444e21.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-5f444e21.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-5f444e21.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-5f444e21.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-7454da29 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-7454da29 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-7454da29 .uagb-ifb-icon svg{fill: #333;}.uagb-block-7454da29.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-7454da29 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-7454da29 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7454da29.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7454da29.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7454da29 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-7454da29 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-7454da29 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7454da29 .uagb-infobox .uagb-ifb-image-content img{border-radius: 50px;}.uagb-block-7454da29.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-7454da29.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-7454da29.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-7454da29.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-7454da29 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-7454da29.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 0px;margin-top: 18px;margin-left: 0px;margin-right: 0px;}.uagb-block-7454da29.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-7454da29 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-7454da29 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-7454da29 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-7454da29 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-7454da29.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-7454da29.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-7454da29 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-7454da29.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-7454da29.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-7454da29.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-7454da29 .uagb-ifb-content .uagb-ifb-image-content > img{width: 48px;}.uagb-block-7454da29.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 48px;}.uagb-block-7454da29 .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 48px;}.uagb-block-7454da29 .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 48px;}.uagb-block-7454da29.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-7454da29 .uagb-ifb-title{text-transform: none;letter-spacing: 0px;}.wp-block-uagb-container.uagb-block-99ee0dee .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-99ee0dee .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-99ee0dee .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-99ee0dee .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-99ee0dee .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-99ee0dee{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-99ee0dee > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-99ee0dee{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;} .uagb-block-ad6b7748 .uag-star-rating{font-size: 20px;} .uagb-block-ad6b7748 .uag-star-rating > span{margin-right: 2px;color: #ccd6df;} .uagb-block-ad6b7748 .uag-star:nth-child(-n+5){color: #f0ad4e;} .uagb-block-ad6b7748 .uag-star-rating__title{margin-right: 10px;} .uagb-block-ad6b7748.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;} .uagb-block-ad6b7748 .uag-star:nth-child(5):before{color: #f0ad4e;width: 0%;position: absolute;content: '\u2605';overflow: hidden;} .uagb-block-ad6b7748 .uag-star:nth-child(5){position: relative;}.uagb-block-73e5f556 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-73e5f556 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-73e5f556 .uagb-ifb-icon svg{fill: #333;}.uagb-block-73e5f556.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-73e5f556 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-73e5f556 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-73e5f556.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-73e5f556.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-73e5f556 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-73e5f556 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-73e5f556 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-73e5f556 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-73e5f556.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-73e5f556.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-73e5f556.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-73e5f556.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-73e5f556 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-73e5f556.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-5);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-73e5f556.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-73e5f556 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-73e5f556 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-73e5f556 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-73e5f556 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-73e5f556.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-73e5f556.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-73e5f556 .uagb-infobox__content-wrap{text-align: center;}.uagb-block-73e5f556.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-73e5f556.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-73e5f556.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-73e5f556.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-833bbe7c .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-833bbe7c .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-833bbe7c .uagb-ifb-icon svg{fill: #333;}.uagb-block-833bbe7c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-833bbe7c .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-833bbe7c .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-833bbe7c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-833bbe7c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-833bbe7c .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-833bbe7c .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-833bbe7c .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-833bbe7c .uagb-infobox .uagb-ifb-image-content img{border-radius: 50px;}.uagb-block-833bbe7c.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-833bbe7c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-833bbe7c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-833bbe7c.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-833bbe7c .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-833bbe7c.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 0px;margin-top: 18px;margin-left: 0px;margin-right: 0px;}.uagb-block-833bbe7c.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-833bbe7c .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-833bbe7c .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-833bbe7c .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-833bbe7c .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-833bbe7c.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-833bbe7c.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-833bbe7c .uagb-infobox__content-wrap{text-align: center;}.uagb-block-833bbe7c.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-833bbe7c.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-833bbe7c.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-833bbe7c .uagb-ifb-content .uagb-ifb-image-content > img{width: 48px;}.uagb-block-833bbe7c.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 48px;}.uagb-block-833bbe7c .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 48px;}.uagb-block-833bbe7c .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 48px;}.uagb-block-833bbe7c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-833bbe7c .uagb-ifb-title{text-transform: none;letter-spacing: 0px;}.wp-block-uagb-container.uagb-block-bb3b162c .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-bb3b162c .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-bb3b162c .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-bb3b162c .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-bb3b162c .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bb3b162c{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bb3b162c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-bb3b162c{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 24px;column-gap: 0px;} .uagb-block-d648d115 .uag-star-rating{font-size: 20px;} .uagb-block-d648d115 .uag-star-rating > span{margin-right: 2px;color: #ccd6df;} .uagb-block-d648d115 .uag-star:nth-child(-n+5){color: #f0ad4e;} .uagb-block-d648d115 .uag-star-rating__title{margin-right: 10px;} .uagb-block-d648d115.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;} .uagb-block-d648d115 .uag-star:nth-child(5):before{color: #f0ad4e;width: 0%;position: absolute;content: '\u2605';overflow: hidden;} .uagb-block-d648d115 .uag-star:nth-child(5){position: relative;}.uagb-block-3c7b265c .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-3c7b265c .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-3c7b265c .uagb-ifb-icon svg{fill: #333;}.uagb-block-3c7b265c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3c7b265c .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3c7b265c .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3c7b265c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3c7b265c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3c7b265c .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3c7b265c .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3c7b265c .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3c7b265c .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-3c7b265c.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3c7b265c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3c7b265c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3c7b265c.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3c7b265c .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-3c7b265c.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-5);margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-3c7b265c.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-3c7b265c .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-3c7b265c .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-3c7b265c .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-3c7b265c .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-3c7b265c.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-3c7b265c.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-3c7b265c .uagb-infobox__content-wrap{text-align: center;}.uagb-block-3c7b265c.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-3c7b265c.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-3c7b265c.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-3c7b265c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-6bf5fe2a .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-6bf5fe2a .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-6bf5fe2a .uagb-ifb-icon svg{fill: #333;}.uagb-block-6bf5fe2a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-6bf5fe2a .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-6bf5fe2a .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6bf5fe2a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6bf5fe2a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6bf5fe2a .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-6bf5fe2a .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-6bf5fe2a .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6bf5fe2a .uagb-infobox .uagb-ifb-image-content img{border-radius: 50px;}.uagb-block-6bf5fe2a.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-6bf5fe2a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-6bf5fe2a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-6bf5fe2a.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 50px;}.uagb-block-6bf5fe2a .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-6bf5fe2a.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 0px;margin-top: 18px;margin-left: 0px;margin-right: 0px;}.uagb-block-6bf5fe2a.wp-block-uagb-info-box .uagb-ifb-desc{color: #ffffff;margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-6bf5fe2a .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-6bf5fe2a .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-6bf5fe2a .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-6bf5fe2a .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-6bf5fe2a.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-6bf5fe2a.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-6bf5fe2a .uagb-infobox__content-wrap{text-align: center;}.uagb-block-6bf5fe2a.uagb-infobox-icon-above-title{text-align: center;}.uagb-block-6bf5fe2a.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-6bf5fe2a.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-6bf5fe2a .uagb-ifb-content .uagb-ifb-image-content > img{width: 48px;}.uagb-block-6bf5fe2a.uagb-infobox__content-wrap .uagb-ifb-image-content > img{width: 48px;}.uagb-block-6bf5fe2a .uagb-ifb-content .uagb-ifb-left-title-image > img{width: 48px;}.uagb-block-6bf5fe2a .uagb-ifb-content .uagb-ifb-right-title-image > img{width: 48px;}.uagb-block-6bf5fe2a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-6bf5fe2a .uagb-ifb-title{text-transform: none;letter-spacing: 0px;}.wp-block-uagb-container.uagb-block-6d512f26 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6d512f26 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6d512f26 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6d512f26 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6d512f26 .uagb-container__video-wrap video{opacity: 0.3;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6d512f26{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6d512f26 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 72px;}.wp-block-uagb-container.uagb-block-6d512f26{box-shadow: 0px 0px   #00000070 ;padding-top: 100px;padding-bottom: 100px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/websitedemos.net\/wp-content\/uploads\/2023\/09\/testimonial-img-bg.jpg);;background-clip: padding-box;row-gap: 0px;column-gap: 72px;}.wp-block-uagb-container.uagb-block-6d512f26::before{content: \"\";position: absolute;pointer-events: none;top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);border-color: inherit;background: var(--ast-global-color-7);opacity: 0.7;}.wp-block-uagb-container.uagb-block-fdda76b5 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-fdda76b5 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-fdda76b5 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-fdda76b5 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-fdda76b5 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-fdda76b5{max-width: 60%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fdda76b5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-fdda76b5{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-864d55c6 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-864d55c6 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-864d55c6 .uagb-ifb-icon svg{fill: #333;}.uagb-block-864d55c6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-864d55c6 .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-864d55c6 .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-864d55c6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-864d55c6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-864d55c6 .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-864d55c6 .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-864d55c6 .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-864d55c6 .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-864d55c6.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-864d55c6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-864d55c6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-864d55c6.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-864d55c6 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 10px;margin-top: 5px;}.uagb-block-864d55c6.wp-block-uagb-info-box .uagb-ifb-title{color: #ffffff;margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-864d55c6.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 20px;}.uagb-block-864d55c6 .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-864d55c6 .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-864d55c6 .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-864d55c6 .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-864d55c6.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-864d55c6.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-864d55c6 .uagb-infobox__content-wrap{text-align: left;}.uagb-block-864d55c6.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-864d55c6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-block-5b8040ed .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5b8040ed .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5b8040ed .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-5b8040ed .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-5b8040ed .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5b8040ed{max-width: 40%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5b8040ed > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-5b8040ed{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.uagb-block-d7d98968.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-d7d98968.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: right;align-items: center;}.wp-block-uagb-buttons .uagb-block-7e0ed373.wp-block-uagb-buttons-child .uagb-buttons-repeater{background: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-7e0ed373 .wp-block-button__link{background: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-7e0ed373 .wp-block-button__link:hover{background: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-7e0ed373 .wp-block-button__link:focus{background: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-7e0ed373 .uagb-button__wrapper .uagb-buttons-repeater{color: #ffffff;}.wp-block-uagb-buttons .uagb-block-7e0ed373 .wp-block-button__link.has-text-color:hover .uagb-button__link{color: #ffffff;}.wp-block-uagb-buttons .uagb-block-7e0ed373 .wp-block-button__link.has-text-color:focus .uagb-button__link{color: #ffffff;}.wp-block-uagb-buttons .uagb-block-7e0ed373 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-7e0ed373 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-7e0ed373 .uagb-buttons-repeater.wp-block-button__link{border-top-left-radius: 4px;border-top-right-radius: 4px;border-bottom-left-radius: 4px;border-bottom-right-radius: 4px;border-color: #333;border-style: none;}.wp-block-uagb-buttons .uagb-block-7e0ed373 .uagb-buttons-repeater.wp-block-button__link:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-7e0ed373 .uagb-buttons-repeater.wp-block-button__link:focus{border-color: #333;}.wp-block-uagb-buttons .uagb-block-7e0ed373.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-left-radius: 4px;border-top-right-radius: 4px;border-bottom-left-radius: 4px;border-bottom-right-radius: 4px;border-color: #333;border-style: none;}.wp-block-uagb-buttons .uagb-block-7e0ed373.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-7e0ed373 .uagb-buttons-repeater .uagb-button__link{color: #ffffff;}.wp-block-uagb-buttons .uagb-block-7e0ed373 .uagb-buttons-repeater:hover .uagb-button__link{color: #ffffff;}.wp-block-uagb-buttons .uagb-block-7e0ed373 .uagb-buttons-repeater:focus .uagb-button__link{color: #ffffff;}.wp-block-uagb-buttons .uagb-block-7e0ed373 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: #ffffff;}.wp-block-uagb-buttons .uagb-block-7e0ed373 .uagb-buttons-repeater:hover .uagb-button__icon > svg{fill: #ffffff;}.wp-block-uagb-buttons .uagb-block-7e0ed373 .uagb-buttons-repeater:focus .uagb-button__icon > svg{fill: #ffffff;}.wp-block-uagb-buttons .uagb-block-7e0ed373 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-7e0ed373 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-7e0ed373 .uagb-button__link{text-transform: normal;text-decoration: none;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-5657136f{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5657136f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-5657136f{padding-top: 80px;padding-bottom: 80px;padding-left: 32px;padding-right: 32px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-5);;}.uagb-block-48b77c69.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 32px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-48b77c69.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-48b77c69.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-48b77c69.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-48b77c69.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-48b77c69 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-48b77c69 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-48b77c69 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-48b77c69 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-48b77c69 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-48b77c69.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-48b77c69.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-48b77c69.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8c4383c7{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8c4383c7 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;row-gap: 0px;column-gap: 40px;}.wp-block-uagb-container.uagb-block-8c4383c7{padding-top: 80px;padding-bottom: 80px;padding-left: 32px;padding-right: 32px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-5);;row-gap: 0px;column-gap: 40px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d4a03254{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d4a03254 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 32px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-d4a03254{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 32px;column-gap: 0px;}.uagb-block-7edef7ac .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-7edef7ac.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-7edef7ac.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-7edef7ac.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7edef7ac.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-7edef7ac.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-7edef7ac .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-7edef7ac .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-7edef7ac .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-7edef7ac .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7edef7ac .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7edef7ac.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-5b4bff5d.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-5b4bff5d.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-de3d4e0e.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: var(--ast-global-color-2);}.wp-block-uagb-buttons .uagb-block-de3d4e0e .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: var(--ast-global-color-2);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-699445d0{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-699445d0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;row-gap: 0px;column-gap: 24px;}.wp-block-uagb-container.uagb-block-699445d0{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;align-items: stretch;row-gap: 0px;column-gap: 24px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-230a853e{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-230a853e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-230a853e{padding-top: 0px;padding-bottom: 40px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 0px;column-gap: 0px;}.uagb-block-1bc337b7.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 170px;height: 250px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9f131a21{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9f131a21 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-9f131a21{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 0px;column-gap: 0px;}.uagb-block-7482949b.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 170px;height: 250px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-323c7320{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-323c7320 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 50px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-323c7320{padding-top: 80px;padding-bottom: 80px;padding-left: 32px;padding-right: 32px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-5);;row-gap: 50px;column-gap: 0px;}.uagb-block-9fbe867d.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 16px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-9fbe867d.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0%;margin-top: 0%;margin-left: 8%;margin-right: 8%;}.uagb-block-9fbe867d.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9fbe867d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-9fbe867d.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-9fbe867d .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-9fbe867d .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-9fbe867d .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-9fbe867d .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9fbe867d .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9fbe867d.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0%;padding-right: 0%;padding-bottom: 0%;padding-left: 0%;}.uagb-block-9fbe867d.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0%;padding-right: 0%;padding-bottom: 0%;padding-left: 0%;}.uagb-block-9fbe867d.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-682319ac{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-682319ac > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;row-gap: 0px;column-gap: 32px;}.wp-block-uagb-container.uagb-block-682319ac{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;align-items: stretch;row-gap: 0px;column-gap: 32px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-71e8fff3{max-width: 47%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-71e8fff3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-71e8fff3{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: ;;align-items: stretch;row-gap: 0px;column-gap: 0px;}.uagb-block-75ccde33.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 214px;height: 300px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9ee67bb3{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9ee67bb3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-9ee67bb3{padding-top: 20px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 24px;column-gap: 0px;}.uagb-block-2ab09e50.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 16px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-2ab09e50.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-2ab09e50.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-2ab09e50.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-2ab09e50.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-2ab09e50 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-2ab09e50 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-2ab09e50 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-2ab09e50 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-2ab09e50 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-2ab09e50.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-2ab09e50.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-2ab09e50.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-64373be9.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-64373be9.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-15570a3f .uagb-buttons-repeater .uagb-button__icon > svg{fill: var(--ast-global-color-2);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a767bc2d{max-width: 47%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a767bc2d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-a767bc2d{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: ;;align-items: stretch;row-gap: 0px;column-gap: 0px;}.uagb-block-b2504f0e.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 214px;height: 300px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9aef83d0{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9aef83d0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-9aef83d0{padding-top: 20px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 24px;column-gap: 0px;}.uagb-block-7e10dc31.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 16px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-7e10dc31.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-7e10dc31.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7e10dc31.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-7e10dc31.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-7e10dc31 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-7e10dc31 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-7e10dc31 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-7e10dc31 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7e10dc31 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7e10dc31.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-7e10dc31.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-7e10dc31.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-66047323.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-66047323.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-5658abd4 .uagb-buttons-repeater .uagb-button__icon > svg{fill: var(--ast-global-color-2);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1add9e25{max-width: 47%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1add9e25 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-1add9e25{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: ;;align-items: stretch;row-gap: 0px;column-gap: 0px;}.uagb-block-cf6d3a59.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 214px;height: 300px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8e1bc111{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8e1bc111 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-8e1bc111{padding-top: 20px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 24px;column-gap: 0px;}.uagb-block-3ce36a5e.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 16px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-3ce36a5e.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-3ce36a5e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3ce36a5e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-3ce36a5e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-3ce36a5e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-3ce36a5e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-3ce36a5e .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-3ce36a5e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3ce36a5e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3ce36a5e.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-3ce36a5e.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-3ce36a5e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-7e724e0b.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-7e724e0b.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-a3d0307e .uagb-buttons-repeater .uagb-button__icon > svg{fill: var(--ast-global-color-2);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1202b3b6{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1202b3b6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 40px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-1202b3b6{padding-top: 80px;padding-bottom: 80px;padding-left: 32px;padding-right: 32px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-5);;row-gap: 40px;column-gap: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f854eaf6{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f854eaf6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;row-gap: 0px;column-gap: 40px;}.wp-block-uagb-container.uagb-block-f854eaf6{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;align-items: stretch;row-gap: 0px;column-gap: 40px;}.uagb-block-4f577d90.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-4f577d90.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-4f577d90.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-4f577d90 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-4f577d90 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-4f577d90 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-4f577d90 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-4f577d90 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-4f577d90.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-fdb34588.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-fdb34588.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-fdb34588.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-fdb34588 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-fdb34588 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-fdb34588 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-fdb34588 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-fdb34588 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-fdb34588.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3c078708{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3c078708 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;row-gap: 0px;column-gap: 24px;}.wp-block-uagb-container.uagb-block-3c078708{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;align-items: stretch;row-gap: 0px;column-gap: 24px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-694ce816{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-694ce816 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-694ce816{padding-top: 24px;padding-bottom: 24px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;border-style: solid;border-color: var(--ast-global-color-6);background-color: var(--ast-global-color-5);;row-gap: 24px;column-gap: 0px;}.uagb-block-d49ddba8.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 16px;margin-top: 20px;margin-left: 0px;margin-right: 0px;}.uagb-block-d49ddba8.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-d49ddba8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 18px;height: 18px;line-height: 18px;font-size: 18px;padding-left: 9px;padding-right: 9px;padding-top: 9px;padding-bottom: 9px;}.uagb-block-d49ddba8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 18px;font-size: 18px;padding-left: 9px;padding-right: 9px;padding-top: 9px;padding-bottom: 9px;}.uagb-block-d49ddba8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 9px;padding-right: 9px;padding-top: 9px;padding-bottom: 9px;}.uagb-block-d49ddba8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 9px;padding-right: 9px;padding-top: 9px;padding-bottom: 9px;}.uagb-block-d49ddba8.uagb-infobox__content-wrap > svg{padding-left: 9px;padding-right: 9px;padding-top: 9px;padding-bottom: 9px;}.uagb-block-d49ddba8 .uagb-ifb-content > svg{padding-left: 9px;padding-right: 9px;padding-top: 9px;padding-bottom: 9px;}.uagb-block-d49ddba8 .uagb-infobox-icon-right:hover > svg{padding-left: 9px;padding-right: 9px;padding-top: 9px;padding-bottom: 9px;}.uagb-block-d49ddba8 .uagb-infobox-icon-left:hover > svg{padding-left: 9px;padding-right: 9px;padding-top: 9px;padding-bottom: 9px;}.uagb-block-d49ddba8.uagb-infobox__content-wrap img{padding-left: 9px;padding-right: 9px;padding-top: 9px;padding-bottom: 9px;}.uagb-block-d49ddba8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d49ddba8 .uagb-ifb-icon{width: 18px;line-height: 18px;}.uagb-block-d49ddba8 .uagb-ifb-icon > span{font-size: 18px;width: 18px;line-height: 18px;}.uagb-block-d49ddba8 .uagb-iconbox-icon-wrap{width: 18px;height: 18px;line-height: 18px;}.uagb-block-d49ddba8 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 18px;line-height: 18px;font-size: 18px;}.uagb-block-d49ddba8 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 18px;line-height: 18px;font-size: 18px;}.uagb-block-d49ddba8.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-d49ddba8.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-d49ddba8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-08292118.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-08292118.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-4fc7d6a2 .uagb-buttons-repeater .uagb-button__icon > svg{fill: var(--ast-global-color-2);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b558d6ab{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b558d6ab > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-b558d6ab{padding-top: 24px;padding-bottom: 24px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;border-style: solid;border-color: var(--ast-global-color-6);background-color: var(--ast-global-color-5);;row-gap: 24px;column-gap: 0px;}.uagb-block-ab9e8375.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 16px;margin-top: 20px;margin-left: 0px;margin-right: 0px;}.uagb-block-ab9e8375.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-ab9e8375.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 18px;height: 18px;line-height: 18px;font-size: 18px;padding-left: 9px;padding-right: 9px;padding-top: 9px;padding-bottom: 9px;}.uagb-block-ab9e8375.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 18px;font-size: 18px;padding-left: 9px;padding-right: 9px;padding-top: 9px;padding-bottom: 9px;}.uagb-block-ab9e8375.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 9px;padding-right: 9px;padding-top: 9px;padding-bottom: 9px;}.uagb-block-ab9e8375.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 9px;padding-right: 9px;padding-top: 9px;padding-bottom: 9px;}.uagb-block-ab9e8375.uagb-infobox__content-wrap > svg{padding-left: 9px;padding-right: 9px;padding-top: 9px;padding-bottom: 9px;}.uagb-block-ab9e8375 .uagb-ifb-content > svg{padding-left: 9px;padding-right: 9px;padding-top: 9px;padding-bottom: 9px;}.uagb-block-ab9e8375 .uagb-infobox-icon-right:hover > svg{padding-left: 9px;padding-right: 9px;padding-top: 9px;padding-bottom: 9px;}.uagb-block-ab9e8375 .uagb-infobox-icon-left:hover > svg{padding-left: 9px;padding-right: 9px;padding-top: 9px;padding-bottom: 9px;}.uagb-block-ab9e8375.uagb-infobox__content-wrap img{padding-left: 9px;padding-right: 9px;padding-top: 9px;padding-bottom: 9px;}.uagb-block-ab9e8375.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-ab9e8375 .uagb-ifb-icon{width: 18px;line-height: 18px;}.uagb-block-ab9e8375 .uagb-ifb-icon > span{font-size: 18px;width: 18px;line-height: 18px;}.uagb-block-ab9e8375 .uagb-iconbox-icon-wrap{width: 18px;height: 18px;line-height: 18px;}.uagb-block-ab9e8375 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 18px;line-height: 18px;font-size: 18px;}.uagb-block-ab9e8375 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 18px;line-height: 18px;font-size: 18px;}.uagb-block-ab9e8375.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-ab9e8375.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-ab9e8375.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-fdf46656.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-fdf46656.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-32051b39 .uagb-buttons-repeater .uagb-button__icon > svg{fill: var(--ast-global-color-2);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-861d4591{max-width: 33%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-861d4591 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-861d4591{padding-top: 24px;padding-bottom: 24px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;border-style: solid;border-color: var(--ast-global-color-6);background-color: var(--ast-global-color-5);;row-gap: 24px;column-gap: 0px;}.uagb-block-2757b255.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 16px;margin-top: 20px;margin-left: 0px;margin-right: 0px;}.uagb-block-2757b255.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-2757b255.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 18px;height: 18px;line-height: 18px;font-size: 18px;padding-left: 9px;padding-right: 9px;padding-top: 9px;padding-bottom: 9px;}.uagb-block-2757b255.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 18px;font-size: 18px;padding-left: 9px;padding-right: 9px;padding-top: 9px;padding-bottom: 9px;}.uagb-block-2757b255.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 9px;padding-right: 9px;padding-top: 9px;padding-bottom: 9px;}.uagb-block-2757b255.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 9px;padding-right: 9px;padding-top: 9px;padding-bottom: 9px;}.uagb-block-2757b255.uagb-infobox__content-wrap > svg{padding-left: 9px;padding-right: 9px;padding-top: 9px;padding-bottom: 9px;}.uagb-block-2757b255 .uagb-ifb-content > svg{padding-left: 9px;padding-right: 9px;padding-top: 9px;padding-bottom: 9px;}.uagb-block-2757b255 .uagb-infobox-icon-right:hover > svg{padding-left: 9px;padding-right: 9px;padding-top: 9px;padding-bottom: 9px;}.uagb-block-2757b255 .uagb-infobox-icon-left:hover > svg{padding-left: 9px;padding-right: 9px;padding-top: 9px;padding-bottom: 9px;}.uagb-block-2757b255.uagb-infobox__content-wrap img{padding-left: 9px;padding-right: 9px;padding-top: 9px;padding-bottom: 9px;}.uagb-block-2757b255.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-2757b255 .uagb-ifb-icon{width: 18px;line-height: 18px;}.uagb-block-2757b255 .uagb-ifb-icon > span{font-size: 18px;width: 18px;line-height: 18px;}.uagb-block-2757b255 .uagb-iconbox-icon-wrap{width: 18px;height: 18px;line-height: 18px;}.uagb-block-2757b255 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 18px;line-height: 18px;font-size: 18px;}.uagb-block-2757b255 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 18px;line-height: 18px;font-size: 18px;}.uagb-block-2757b255.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-2757b255.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-2757b255.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-fd943482.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-fd943482.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-941fa188 .uagb-buttons-repeater .uagb-button__icon > svg{fill: var(--ast-global-color-2);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-dd28d95c{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dd28d95c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 50px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-dd28d95c{padding-top: 80px;padding-bottom: 80px;padding-left: 32px;padding-right: 32px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-5);;row-gap: 50px;column-gap: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-609fec64{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-609fec64 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-609fec64{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-72f13e20{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-72f13e20 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-72f13e20{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 0px;column-gap: 0px;}.uagb-block-1882db2b.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-1882db2b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-1882db2b.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-1882db2b .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-1882db2b .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-1882db2b .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-1882db2b .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-1882db2b .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-1882db2b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4a8d035b{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4a8d035b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-4a8d035b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 0px;column-gap: 0px;}.uagb-block-3a19b4ea.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3a19b4ea.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-3a19b4ea.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-3a19b4ea .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-3a19b4ea .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-3a19b4ea .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-3a19b4ea .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3a19b4ea .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3a19b4ea.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8f6c422d{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8f6c422d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 0px;column-gap: 48px;}.wp-block-uagb-container.uagb-block-8f6c422d{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 0px;column-gap: 48px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0ba6d01d{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0ba6d01d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-0ba6d01d{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 0px;column-gap: 0px;}.uagb-block-4e75022d.wp-block-uagb-image--layout-default figure img{border-style: none;}.uagb-block-4e75022d.wp-block-uagb-image--layout-overlay figure img{border-style: none;}.uagb-block-4e75022d.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 600px;height: 450px;}.uagb-block-4e75022d.wp-block-uagb-image{text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-4e75022d .wp-block-uagb-image__figure{align-items: flex-start;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-56e1cd58{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-56e1cd58 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 32px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-56e1cd58{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 32px;column-gap: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f2a241b1{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f2a241b1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;column-gap: 32px;}.wp-block-uagb-container.uagb-block-f2a241b1{padding-top: 10px;padding-bottom: 30px;padding-left: 10px;padding-right: 10px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;border-style: solid;border-color: var(--ast-global-color-6);column-gap: 32px;}.uagb-block-c5554396.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-c5554396.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 16px;height: 16px;line-height: 16px;font-size: 16px;}.uagb-block-c5554396.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 16px;font-size: 16px;}.uagb-block-c5554396.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-c5554396 .uagb-ifb-icon{width: 16px;line-height: 16px;}.uagb-block-c5554396 .uagb-ifb-icon > span{font-size: 16px;width: 16px;line-height: 16px;}.uagb-block-c5554396 .uagb-iconbox-icon-wrap{width: 16px;height: 16px;line-height: 16px;}.uagb-block-c5554396 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;}.uagb-block-c5554396 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;}.uagb-block-c5554396.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-c5554396.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-c5554396.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-b685501a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 16px;height: 16px;line-height: 16px;font-size: 16px;}.uagb-block-b685501a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 16px;font-size: 16px;}.uagb-block-b685501a.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b685501a .uagb-ifb-icon{width: 16px;line-height: 16px;}.uagb-block-b685501a .uagb-ifb-icon > span{font-size: 16px;width: 16px;line-height: 16px;}.uagb-block-b685501a .uagb-iconbox-icon-wrap{width: 16px;height: 16px;line-height: 16px;}.uagb-block-b685501a .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;}.uagb-block-b685501a .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;}.uagb-block-b685501a.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-b685501a.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-b685501a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-737a9fe3{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-737a9fe3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;column-gap: 32px;}.wp-block-uagb-container.uagb-block-737a9fe3{padding-top: 0px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;column-gap: 32px;}.uagb-block-b31d2911.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-b31d2911.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 16px;height: 16px;line-height: 16px;font-size: 16px;}.uagb-block-b31d2911.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 16px;font-size: 16px;}.uagb-block-b31d2911.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b31d2911 .uagb-ifb-icon{width: 16px;line-height: 16px;}.uagb-block-b31d2911 .uagb-ifb-icon > span{font-size: 16px;width: 16px;line-height: 16px;}.uagb-block-b31d2911 .uagb-iconbox-icon-wrap{width: 16px;height: 16px;line-height: 16px;}.uagb-block-b31d2911 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;}.uagb-block-b31d2911 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;}.uagb-block-b31d2911.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-b31d2911.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-b31d2911.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-75008db2.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 16px;height: 16px;line-height: 16px;font-size: 16px;}.uagb-block-75008db2.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 16px;font-size: 16px;}.uagb-block-75008db2.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-75008db2 .uagb-ifb-icon{width: 16px;line-height: 16px;}.uagb-block-75008db2 .uagb-ifb-icon > span{font-size: 16px;width: 16px;line-height: 16px;}.uagb-block-75008db2 .uagb-iconbox-icon-wrap{width: 16px;height: 16px;line-height: 16px;}.uagb-block-75008db2 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;}.uagb-block-75008db2 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;}.uagb-block-75008db2.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0875eb55{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0875eb55 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;column-gap: 40px;}.wp-block-uagb-container.uagb-block-0875eb55{padding-top: 80px;padding-bottom: 80px;padding-left: 32px;padding-right: 32px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-5);;column-gap: 40px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-abcd4e61{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-abcd4e61 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-abcd4e61{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.uagb-block-47b7c002.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 16px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-47b7c002.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0%;margin-top: 0%;margin-left: 8%;margin-right: 8%;}.uagb-block-47b7c002.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-47b7c002.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-47b7c002.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-47b7c002 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-47b7c002 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-47b7c002 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-47b7c002 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-47b7c002 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-47b7c002.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0%;padding-right: 0%;padding-bottom: 0%;padding-left: 0%;}.uagb-block-47b7c002.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0%;padding-right: 0%;padding-bottom: 0%;padding-left: 0%;}.uagb-block-47b7c002.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f837bf6f{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f837bf6f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 32px;}.wp-block-uagb-container.uagb-block-f837bf6f{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 32px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-27788532{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-27788532 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-27788532{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-ead7767b.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 16px;margin-top: 20px;margin-left: 0px;margin-right: 0px;}.uagb-block-ead7767b.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-ead7767b.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 14px;height: 14px;line-height: 14px;font-size: 14px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-ead7767b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 14px;font-size: 14px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-ead7767b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-ead7767b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-ead7767b.uagb-infobox__content-wrap > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-ead7767b .uagb-ifb-content > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-ead7767b .uagb-infobox-icon-right:hover > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-ead7767b .uagb-infobox-icon-left:hover > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-ead7767b.uagb-infobox__content-wrap img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-ead7767b.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-ead7767b .uagb-ifb-icon{width: 14px;line-height: 14px;}.uagb-block-ead7767b .uagb-ifb-icon > span{font-size: 14px;width: 14px;line-height: 14px;}.uagb-block-ead7767b .uagb-iconbox-icon-wrap{width: 14px;height: 14px;line-height: 14px;}.uagb-block-ead7767b .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 14px;line-height: 14px;font-size: 14px;}.uagb-block-ead7767b .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 14px;line-height: 14px;font-size: 14px;}.uagb-block-ead7767b.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-ead7767b.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-ead7767b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-200adade{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-200adade > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-200adade{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-14c90ca5.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 16px;margin-top: 20px;margin-left: 0px;margin-right: 0px;}.uagb-block-14c90ca5.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-14c90ca5.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 14px;height: 14px;line-height: 14px;font-size: 14px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-14c90ca5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 14px;font-size: 14px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-14c90ca5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-14c90ca5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-14c90ca5.uagb-infobox__content-wrap > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-14c90ca5 .uagb-ifb-content > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-14c90ca5 .uagb-infobox-icon-right:hover > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-14c90ca5 .uagb-infobox-icon-left:hover > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-14c90ca5.uagb-infobox__content-wrap img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-14c90ca5.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-14c90ca5 .uagb-ifb-icon{width: 14px;line-height: 14px;}.uagb-block-14c90ca5 .uagb-ifb-icon > span{font-size: 14px;width: 14px;line-height: 14px;}.uagb-block-14c90ca5 .uagb-iconbox-icon-wrap{width: 14px;height: 14px;line-height: 14px;}.uagb-block-14c90ca5 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 14px;line-height: 14px;font-size: 14px;}.uagb-block-14c90ca5 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 14px;line-height: 14px;font-size: 14px;}.uagb-block-14c90ca5.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-14c90ca5.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-14c90ca5.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-fd033695{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fd033695 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-fd033695{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-caa994d6.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 16px;margin-top: 20px;margin-left: 0px;margin-right: 0px;}.uagb-block-caa994d6.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-caa994d6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 14px;height: 14px;line-height: 14px;font-size: 14px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-caa994d6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 14px;font-size: 14px;padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-caa994d6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-caa994d6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-caa994d6.uagb-infobox__content-wrap > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-caa994d6 .uagb-ifb-content > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-caa994d6 .uagb-infobox-icon-right:hover > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-caa994d6 .uagb-infobox-icon-left:hover > svg{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-caa994d6.uagb-infobox__content-wrap img{padding-left: 10px;padding-right: 10px;padding-top: 10px;padding-bottom: 10px;}.uagb-block-caa994d6.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-caa994d6 .uagb-ifb-icon{width: 14px;line-height: 14px;}.uagb-block-caa994d6 .uagb-ifb-icon > span{font-size: 14px;width: 14px;line-height: 14px;}.uagb-block-caa994d6 .uagb-iconbox-icon-wrap{width: 14px;height: 14px;line-height: 14px;}.uagb-block-caa994d6 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 14px;line-height: 14px;font-size: 14px;}.uagb-block-caa994d6 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 14px;line-height: 14px;font-size: 14px;}.uagb-block-caa994d6.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-caa994d6.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-caa994d6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e8a2a613{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e8a2a613 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 50px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-e8a2a613{padding-top: 80px;padding-bottom: 80px;padding-left: 32px;padding-right: 32px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-5);;row-gap: 50px;column-gap: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-51e2c002{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-51e2c002 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-51e2c002{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 0px;column-gap: 0px;}.uagb-block-fc90a4a2.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 16px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-fc90a4a2.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0%;margin-top: 0%;margin-left: 8%;margin-right: 8%;}.uagb-block-fc90a4a2.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-fc90a4a2.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-fc90a4a2.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-fc90a4a2 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-fc90a4a2 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-fc90a4a2 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-fc90a4a2 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-fc90a4a2 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-fc90a4a2.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0%;padding-right: 0%;padding-bottom: 0%;padding-left: 0%;}.uagb-block-fc90a4a2.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0%;padding-right: 0%;padding-bottom: 0%;padding-left: 0%;}.uagb-block-fc90a4a2.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f2f686c0{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f2f686c0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-f2f686c0{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-03da51f9{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-03da51f9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;flex-wrap: wrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-03da51f9{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;align-items: stretch;flex-wrap: wrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bca0ac81{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bca0ac81 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 0px;column-gap: 24px;}.wp-block-uagb-container.uagb-block-bca0ac81{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;row-gap: 0px;column-gap: 24px;}.uagb-block-e4fcfe5f.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 340px;height: 340px;}.uagb-block-0a7ee55f.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 340px;height: 340px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-42ebd4f6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-42ebd4f6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 0px;column-gap: 24px;}.wp-block-uagb-container.uagb-block-42ebd4f6{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;row-gap: 0px;column-gap: 24px;}.uagb-block-4a7f1049.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 340px;height: 340px;}.uagb-block-271d56c7.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 340px;height: 340px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3560d1a5{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3560d1a5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;flex-wrap: wrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-3560d1a5{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;align-items: stretch;flex-wrap: wrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5894fa70{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5894fa70 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 0px;column-gap: 24px;}.wp-block-uagb-container.uagb-block-5894fa70{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;row-gap: 0px;column-gap: 24px;}.uagb-block-6770cd95.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 340px;height: 340px;}.uagb-block-b201bcee.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 340px;height: 340px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0a3f9b21{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0a3f9b21 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 0px;column-gap: 24px;}.wp-block-uagb-container.uagb-block-0a3f9b21{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;row-gap: 0px;column-gap: 24px;}.uagb-block-728c8074.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 340px;height: 340px;}.uagb-block-9206fcbd.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 340px;height: 340px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7904eaf3{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7904eaf3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 32px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-7904eaf3{padding-top: 80px;padding-bottom: 80px;padding-left: 32px;padding-right: 32px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-5);;row-gap: 32px;column-gap: 0px;}.uagb-block-18e6815d.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 16px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-18e6815d.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0%;margin-top: 0%;margin-left: 8%;margin-right: 8%;}.uagb-block-18e6815d.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-18e6815d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-18e6815d.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-18e6815d .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-18e6815d .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-18e6815d .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-18e6815d .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-18e6815d .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-18e6815d.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0%;padding-right: 0%;padding-bottom: 0%;padding-left: 0%;}.uagb-block-18e6815d.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0%;padding-right: 0%;padding-bottom: 0%;padding-left: 0%;}.uagb-block-18e6815d.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ec11566e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ec11566e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-ec11566e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-08bf843c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-08bf843c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 0px;column-gap: 24px;}.wp-block-uagb-container.uagb-block-08bf843c{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 0px;column-gap: 24px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-920cad8c{max-width: 68%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-920cad8c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-920cad8c{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 0px;column-gap: 0px;}.uagb-block-5bb0bbc0.wp-block-uagb-image--layout-default figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-5bb0bbc0.wp-block-uagb-image--layout-overlay figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-5bb0bbc0.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 792px;height: 350px;}.uagb-block-5bb0bbc0.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-5bb0bbc0 .wp-block-uagb-image__figure{align-items: flex-start;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e0323075{max-width: 32%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e0323075 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-e0323075{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 0px;column-gap: 0px;}.uagb-block-9cbc911a.wp-block-uagb-image--layout-default figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-9cbc911a.wp-block-uagb-image--layout-overlay figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-9cbc911a.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 400px;height: 350px;}.uagb-block-9cbc911a.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-9cbc911a .wp-block-uagb-image__figure{align-items: flex-start;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-01bd5354{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-01bd5354 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 0px;column-gap: 24px;}.wp-block-uagb-container.uagb-block-01bd5354{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 0px;column-gap: 24px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-aa24ab14{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-aa24ab14 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-aa24ab14{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 0px;column-gap: 0px;}.uagb-block-df48cc3c.wp-block-uagb-image--layout-default figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-df48cc3c.wp-block-uagb-image--layout-overlay figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-df48cc3c.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 400px;height: 350px;}.uagb-block-df48cc3c.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c6438229{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c6438229 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-c6438229{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 0px;column-gap: 0px;}.uagb-block-34281fbc.wp-block-uagb-image--layout-default figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-34281fbc.wp-block-uagb-image--layout-overlay figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-34281fbc.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 792px;height: 350px;}.uagb-block-34281fbc.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a37cb94d{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a37cb94d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;row-gap: 0px;column-gap: 40px;}.wp-block-uagb-container.uagb-block-a37cb94d{padding-top: 80px;padding-bottom: 80px;padding-left: 32px;padding-right: 32px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-5);;row-gap: 0px;column-gap: 40px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-02b2643c{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-02b2643c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 40px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-02b2643c{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 40px;column-gap: 0px;}.uagb-block-cf9e68d1 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-cf9e68d1.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-cf9e68d1.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-cf9e68d1.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-cf9e68d1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-cf9e68d1.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-cf9e68d1 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-cf9e68d1 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-cf9e68d1 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-cf9e68d1 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-cf9e68d1 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-cf9e68d1.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0db1fe01{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0db1fe01 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 16px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-0db1fe01{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 16px;column-gap: 0px;}.uagb-block-c5887fb5.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 8px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-c5887fb5.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-c5887fb5.uagb-infobox__content-wrap .uagb-ifb-separator{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-c5887fb5.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;}.uagb-block-c5887fb5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 20px;font-size: 20px;}.uagb-block-c5887fb5 .uagb-ifb-separator{width: 100%;}.uagb-block-c5887fb5.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-c5887fb5 .uagb-ifb-icon{width: 20px;line-height: 20px;}.uagb-block-c5887fb5 .uagb-ifb-icon > span{font-size: 20px;width: 20px;line-height: 20px;}.uagb-block-c5887fb5 .uagb-iconbox-icon-wrap{width: 20px;height: 20px;line-height: 20px;}.uagb-block-c5887fb5 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 20px;line-height: 20px;font-size: 20px;}.uagb-block-c5887fb5 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 20px;line-height: 20px;font-size: 20px;}.uagb-block-c5887fb5.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-8320b8f4.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 8px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-8320b8f4.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-8320b8f4.uagb-infobox__content-wrap .uagb-ifb-separator{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-8320b8f4.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;}.uagb-block-8320b8f4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 20px;font-size: 20px;}.uagb-block-8320b8f4 .uagb-ifb-separator{width: 100%;}.uagb-block-8320b8f4.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-8320b8f4 .uagb-ifb-icon{width: 20px;line-height: 20px;}.uagb-block-8320b8f4 .uagb-ifb-icon > span{font-size: 20px;width: 20px;line-height: 20px;}.uagb-block-8320b8f4 .uagb-iconbox-icon-wrap{width: 20px;height: 20px;line-height: 20px;}.uagb-block-8320b8f4 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 20px;line-height: 20px;font-size: 20px;}.uagb-block-8320b8f4 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 20px;line-height: 20px;font-size: 20px;}.uagb-block-8320b8f4.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-26acf763.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 8px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-26acf763.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-26acf763.uagb-infobox__content-wrap .uagb-ifb-separator{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-26acf763.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;}.uagb-block-26acf763.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 20px;font-size: 20px;}.uagb-block-26acf763 .uagb-ifb-separator{width: 100%;}.uagb-block-26acf763.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-26acf763 .uagb-ifb-icon{width: 20px;line-height: 20px;}.uagb-block-26acf763 .uagb-ifb-icon > span{font-size: 20px;width: 20px;line-height: 20px;}.uagb-block-26acf763 .uagb-iconbox-icon-wrap{width: 20px;height: 20px;line-height: 20px;}.uagb-block-26acf763 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 20px;line-height: 20px;font-size: 20px;}.uagb-block-26acf763 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 20px;line-height: 20px;font-size: 20px;}.uagb-block-26acf763.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-25055c6b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-25055c6b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-25055c6b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 0px;column-gap: 0px;}.uagb-block-2b404dfd.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 600px;height: 450px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-45f809f9{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-45f809f9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;}.wp-block-uagb-container.uagb-block-45f809f9{padding-top: 80px;padding-bottom: 80px;padding-left: 32px;padding-right: 32px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-clip: padding-box;}.wp-block-uagb-container.uagb-block-45f809f9::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);}.wp-block-uagb-container.uagb-block-45f809f9.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-45f809f9.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.uagb-block-25ee98b8 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-25ee98b8.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 24px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-25ee98b8.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0%;margin-top: 0%;margin-left: 8%;margin-right: 8%;}.uagb-block-25ee98b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-25ee98b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-25ee98b8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-25ee98b8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-25ee98b8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-25ee98b8 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-25ee98b8 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-25ee98b8 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-25ee98b8.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-25ee98b8.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-25ee98b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f9770f2e{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f9770f2e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;}.wp-block-uagb-container.uagb-block-f9770f2e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;}.wp-block-uagb-container.uagb-block-f9770f2e.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-f9770f2e.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a49f2642{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a49f2642 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-a49f2642{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-a49f2642.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-a49f2642.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;} .uagb-block-9d745acf.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;} .uagb-block-9d745acf .uag-star-rating__title {margin-bottom: 0;} .uagb-block-9d745acf .uag-star-rating__title{margin-right: 10px;} .uagb-block-9d745acf .uag-star-rating{font-size: 22px;}.uagb-block-5f444e21.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-5f444e21.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-5f444e21.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-5f444e21.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-5f444e21 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-5f444e21 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-5f444e21 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-5f444e21 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-5f444e21 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-5f444e21.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-5f444e21.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-5f444e21.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-7454da29.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 10px;margin-left: 0px;margin-right: 0px;}.uagb-block-7454da29.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-7454da29.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7454da29.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7454da29.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7454da29.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7454da29.uagb-infobox__content-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7454da29 .uagb-ifb-content > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7454da29 .uagb-infobox-icon-right:hover > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7454da29 .uagb-infobox-icon-left:hover > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7454da29.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-7454da29.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-7454da29 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-7454da29 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-7454da29 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-7454da29 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7454da29 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7454da29.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-7454da29.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-7454da29 .uagb-ifb-content .uagb-ifb-image-content img{width: 48px;}.uagb-block-7454da29.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 48px;}.uagb-block-7454da29 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 48px;}.uagb-block-7454da29 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 48px;}.uagb-block-7454da29.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-99ee0dee{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-99ee0dee > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-99ee0dee{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-99ee0dee.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-99ee0dee.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;} .uagb-block-ad6b7748.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;} .uagb-block-ad6b7748 .uag-star-rating__title {margin-bottom: 0;} .uagb-block-ad6b7748 .uag-star-rating__title{margin-right: 10px;} .uagb-block-ad6b7748 .uag-star-rating{font-size: 22px;}.uagb-block-73e5f556.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-73e5f556.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-73e5f556.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-73e5f556.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-73e5f556 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-73e5f556 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-73e5f556 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-73e5f556 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-73e5f556 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-73e5f556.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-73e5f556.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-73e5f556.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-833bbe7c.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 10px;margin-left: 0px;margin-right: 0px;}.uagb-block-833bbe7c.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-833bbe7c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-833bbe7c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-833bbe7c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-833bbe7c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-833bbe7c.uagb-infobox__content-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-833bbe7c .uagb-ifb-content > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-833bbe7c .uagb-infobox-icon-right:hover > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-833bbe7c .uagb-infobox-icon-left:hover > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-833bbe7c.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-833bbe7c.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-833bbe7c .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-833bbe7c .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-833bbe7c .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-833bbe7c .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-833bbe7c .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-833bbe7c.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-833bbe7c.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-833bbe7c .uagb-ifb-content .uagb-ifb-image-content img{width: 48px;}.uagb-block-833bbe7c.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 48px;}.uagb-block-833bbe7c .uagb-ifb-content .uagb-ifb-left-title-image img{width: 48px;}.uagb-block-833bbe7c .uagb-ifb-content .uagb-ifb-right-title-image img{width: 48px;}.uagb-block-833bbe7c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bb3b162c{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bb3b162c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-bb3b162c{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-bb3b162c.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-bb3b162c.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;} .uagb-block-d648d115.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;} .uagb-block-d648d115 .uag-star-rating__title {margin-bottom: 0;} .uagb-block-d648d115 .uag-star-rating__title{margin-right: 10px;} .uagb-block-d648d115 .uag-star-rating{font-size: 22px;}.uagb-block-3c7b265c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3c7b265c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-3c7b265c.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-3c7b265c .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-3c7b265c .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-3c7b265c .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-3c7b265c .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3c7b265c .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3c7b265c.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-3c7b265c.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-3c7b265c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-6bf5fe2a.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 10px;margin-left: 0px;margin-right: 0px;}.uagb-block-6bf5fe2a.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-6bf5fe2a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6bf5fe2a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6bf5fe2a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6bf5fe2a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6bf5fe2a.uagb-infobox__content-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6bf5fe2a .uagb-ifb-content > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6bf5fe2a .uagb-infobox-icon-right:hover > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6bf5fe2a .uagb-infobox-icon-left:hover > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6bf5fe2a.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6bf5fe2a.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-6bf5fe2a .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-6bf5fe2a .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-6bf5fe2a .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-6bf5fe2a .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-6bf5fe2a .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-6bf5fe2a.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-6bf5fe2a.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-6bf5fe2a .uagb-ifb-content .uagb-ifb-image-content img{width: 48px;}.uagb-block-6bf5fe2a.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 48px;}.uagb-block-6bf5fe2a .uagb-ifb-content .uagb-ifb-left-title-image img{width: 48px;}.uagb-block-6bf5fe2a .uagb-ifb-content .uagb-ifb-right-title-image img{width: 48px;}.uagb-block-6bf5fe2a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6d512f26{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6d512f26 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-6d512f26{padding-top: 64px;padding-bottom: 64px;padding-left: 32px;padding-right: 32px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-clip: padding-box;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-6d512f26::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-fdda76b5{max-width: 70%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fdda76b5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-fdda76b5{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 0px;column-gap: 0px;}.uagb-block-864d55c6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-864d55c6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-864d55c6.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-864d55c6 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-864d55c6 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-864d55c6 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-864d55c6 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-864d55c6 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-864d55c6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5b8040ed{max-width: 30%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5b8040ed > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-5b8040ed{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 0px;column-gap: 0px;}.uagb-block-d7d98968.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: right;align-items: center;}.uagb-block-d7d98968.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-7e0ed373.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: none;border-color: #333;}.wp-block-uagb-buttons .uagb-block-7e0ed373 .uagb-buttons-repeater.wp-block-button__link{border-style: none;border-color: #333;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-5657136f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5657136f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-5657136f{padding-top: 64px;padding-bottom: 64px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-5);;}.uagb-block-48b77c69.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 28px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-48b77c69.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-48b77c69.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-48b77c69.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-48b77c69 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-48b77c69 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-48b77c69.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-48b77c69 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-48b77c69 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-48b77c69 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-48b77c69.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-48b77c69.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-48b77c69.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8c4383c7{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8c4383c7 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;flex-wrap: wrap;row-gap: 40px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-8c4383c7{padding-top: 64px;padding-bottom: 64px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 40px;column-gap: 0px;order: initial;background-color: var(--ast-global-color-5);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d4a03254{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-d4a03254 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-d4a03254{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;column-gap: 0px;order: initial;flex-wrap: wrap;}.uagb-block-7edef7ac .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-7edef7ac.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 16px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-7edef7ac.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7edef7ac.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-7edef7ac .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7edef7ac .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7edef7ac.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-7edef7ac .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-7edef7ac .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-7edef7ac .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-7edef7ac.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-5b4bff5d.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-5b4bff5d.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-de3d4e0e.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: var(--ast-global-color-2);}.wp-block-uagb-buttons .uagb-block-de3d4e0e .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: var(--ast-global-color-2);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-699445d0{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-699445d0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;flex-wrap: nowrap;row-gap: 0px;column-gap: 24px;}.wp-block-uagb-container.uagb-block-699445d0{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 0px;column-gap: 24px;order: initial;flex-direction: row;align-items: stretch;flex-wrap: nowrap;}.wp-block-uagb-container.uagb-block-699445d0.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-699445d0.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-230a853e{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-230a853e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-230a853e{padding-top: 0px;padding-bottom: 40px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 0px;column-gap: 0px;order: initial;flex-wrap: wrap;}.uagb-block-1bc337b7.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 600px;height: 250px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9f131a21{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9f131a21 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-9f131a21{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 0px;column-gap: 0px;order: initial;flex-wrap: wrap;}.uagb-block-7482949b.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 600px;height: 250px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-323c7320{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-323c7320 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 40px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-323c7320{padding-top: 64px;padding-bottom: 64px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 40px;column-gap: 0px;order: initial;background-color: var(--ast-global-color-5);;}.uagb-block-9fbe867d.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-9fbe867d.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-9fbe867d.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9fbe867d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-9fbe867d .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9fbe867d .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-9fbe867d.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-9fbe867d .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-9fbe867d .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-9fbe867d .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-9fbe867d.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-9fbe867d.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-9fbe867d.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-682319ac{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-682319ac > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;flex-wrap: wrap;row-gap: 30px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-682319ac{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 30px;column-gap: 0px;order: initial;align-items: stretch;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-71e8fff3{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-71e8fff3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;flex-wrap: wrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-71e8fff3{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 0px;column-gap: 0px;order: initial;background-color: ;;align-items: stretch;flex-wrap: wrap;}.uagb-block-75ccde33.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 600px;height: 300px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9ee67bb3{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9ee67bb3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-9ee67bb3{padding-top: 20px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;column-gap: 0px;order: initial;flex-wrap: wrap;}.uagb-block-2ab09e50.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-2ab09e50.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-2ab09e50.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-2ab09e50.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-2ab09e50 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-2ab09e50 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-2ab09e50.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-2ab09e50 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-2ab09e50 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-2ab09e50 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-2ab09e50.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-2ab09e50.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-2ab09e50.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-64373be9.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-64373be9.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-15570a3f .uagb-buttons-repeater .uagb-button__icon > svg{fill: var(--ast-global-color-2);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a767bc2d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a767bc2d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;flex-wrap: wrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-a767bc2d{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 0px;column-gap: 0px;order: initial;background-color: ;;align-items: stretch;flex-wrap: wrap;}.uagb-block-b2504f0e.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 600px;height: 300px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9aef83d0{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9aef83d0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-9aef83d0{padding-top: 20px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;column-gap: 0px;order: initial;flex-wrap: wrap;}.uagb-block-7e10dc31.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-7e10dc31.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-7e10dc31.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7e10dc31.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-7e10dc31 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7e10dc31 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7e10dc31.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-7e10dc31 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-7e10dc31 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-7e10dc31 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-7e10dc31.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-7e10dc31.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-7e10dc31.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-66047323.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-66047323.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-5658abd4 .uagb-buttons-repeater .uagb-button__icon > svg{fill: var(--ast-global-color-2);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1add9e25{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1add9e25 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;flex-wrap: wrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-1add9e25{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 0px;column-gap: 0px;order: initial;background-color: ;;align-items: stretch;flex-wrap: wrap;}.uagb-block-cf6d3a59.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 600px;height: 300px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8e1bc111{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8e1bc111 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-8e1bc111{padding-top: 20px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;column-gap: 0px;order: initial;flex-wrap: wrap;}.uagb-block-3ce36a5e.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-3ce36a5e.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-3ce36a5e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3ce36a5e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-3ce36a5e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3ce36a5e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3ce36a5e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-3ce36a5e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-3ce36a5e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-3ce36a5e .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-3ce36a5e.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-3ce36a5e.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-3ce36a5e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-7e724e0b.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-7e724e0b.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-a3d0307e .uagb-buttons-repeater .uagb-button__icon > svg{fill: var(--ast-global-color-2);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1202b3b6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1202b3b6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 40px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-1202b3b6{padding-top: 64px;padding-bottom: 64px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 40px;column-gap: 0px;order: initial;background-color: var(--ast-global-color-5);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f854eaf6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f854eaf6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;flex-wrap: wrap;row-gap: 12px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-f854eaf6{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 12px;column-gap: 0px;order: initial;align-items: stretch;flex-wrap: wrap;}.uagb-block-4f577d90.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-4f577d90.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-4f577d90 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-4f577d90 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-4f577d90.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-4f577d90 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-4f577d90 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-4f577d90 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-4f577d90.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-fdb34588.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-fdb34588.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-fdb34588 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-fdb34588 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-fdb34588.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-fdb34588 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-fdb34588 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-fdb34588 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-fdb34588.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3c078708{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3c078708 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;flex-wrap: wrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-3c078708{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;column-gap: 0px;order: initial;align-items: stretch;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-694ce816{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-694ce816 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-694ce816{padding-top: 24px;padding-bottom: 24px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 20px;column-gap: 0px;order: initial;border-style: solid;border-color: var(--ast-global-color-6);background-color: var(--ast-global-color-5);;flex-wrap: wrap;}.uagb-block-d49ddba8.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 12px;margin-top: 16px;margin-left: 0px;margin-right: 0px;}.uagb-block-d49ddba8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 16px;height: 16px;line-height: 16px;font-size: 16px;padding-left: 8px;padding-right: 8px;padding-top: 8px;padding-bottom: 8px;}.uagb-block-d49ddba8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 16px;font-size: 16px;padding-left: 8px;padding-right: 8px;padding-top: 8px;padding-bottom: 8px;}.uagb-block-d49ddba8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 8px;padding-right: 8px;padding-top: 8px;padding-bottom: 8px;}.uagb-block-d49ddba8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 8px;padding-right: 8px;padding-top: 8px;padding-bottom: 8px;}.uagb-block-d49ddba8.uagb-infobox__content-wrap > svg{padding-left: 8px;padding-right: 8px;padding-top: 8px;padding-bottom: 8px;}.uagb-block-d49ddba8 .uagb-ifb-content > svg{padding-left: 8px;padding-right: 8px;padding-top: 8px;padding-bottom: 8px;}.uagb-block-d49ddba8 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;padding-left: 8px;padding-right: 8px;padding-top: 8px;padding-bottom: 8px;}.uagb-block-d49ddba8 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;padding-left: 8px;padding-right: 8px;padding-top: 8px;padding-bottom: 8px;}.uagb-block-d49ddba8.uagb-infobox__content-wrap img{padding-left: 8px;padding-right: 8px;padding-top: 8px;padding-bottom: 8px;}.uagb-block-d49ddba8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-d49ddba8 .uagb-ifb-icon{width: 16px;line-height: 16px;}.uagb-block-d49ddba8 .uagb-ifb-icon > span{font-size: 16px;width: 16px;line-height: 16px;}.uagb-block-d49ddba8 .uagb-iconbox-icon-wrap{width: 16px;height: 16px;line-height: 16px;}.uagb-block-d49ddba8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-08292118.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-08292118.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-4fc7d6a2 .uagb-buttons-repeater .uagb-button__icon > svg{fill: var(--ast-global-color-2);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b558d6ab{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b558d6ab > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-b558d6ab{padding-top: 24px;padding-bottom: 24px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 20px;column-gap: 0px;order: initial;border-style: solid;border-color: var(--ast-global-color-6);background-color: var(--ast-global-color-5);;flex-wrap: wrap;}.uagb-block-ab9e8375.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 12px;margin-top: 16px;margin-left: 0px;margin-right: 0px;}.uagb-block-ab9e8375.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 16px;height: 16px;line-height: 16px;font-size: 16px;padding-left: 8px;padding-right: 8px;padding-top: 8px;padding-bottom: 8px;}.uagb-block-ab9e8375.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 16px;font-size: 16px;padding-left: 8px;padding-right: 8px;padding-top: 8px;padding-bottom: 8px;}.uagb-block-ab9e8375.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 8px;padding-right: 8px;padding-top: 8px;padding-bottom: 8px;}.uagb-block-ab9e8375.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 8px;padding-right: 8px;padding-top: 8px;padding-bottom: 8px;}.uagb-block-ab9e8375.uagb-infobox__content-wrap > svg{padding-left: 8px;padding-right: 8px;padding-top: 8px;padding-bottom: 8px;}.uagb-block-ab9e8375 .uagb-ifb-content > svg{padding-left: 8px;padding-right: 8px;padding-top: 8px;padding-bottom: 8px;}.uagb-block-ab9e8375 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;padding-left: 8px;padding-right: 8px;padding-top: 8px;padding-bottom: 8px;}.uagb-block-ab9e8375 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;padding-left: 8px;padding-right: 8px;padding-top: 8px;padding-bottom: 8px;}.uagb-block-ab9e8375.uagb-infobox__content-wrap img{padding-left: 8px;padding-right: 8px;padding-top: 8px;padding-bottom: 8px;}.uagb-block-ab9e8375.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-ab9e8375 .uagb-ifb-icon{width: 16px;line-height: 16px;}.uagb-block-ab9e8375 .uagb-ifb-icon > span{font-size: 16px;width: 16px;line-height: 16px;}.uagb-block-ab9e8375 .uagb-iconbox-icon-wrap{width: 16px;height: 16px;line-height: 16px;}.uagb-block-ab9e8375.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-fdf46656.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-fdf46656.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-32051b39 .uagb-buttons-repeater .uagb-button__icon > svg{fill: var(--ast-global-color-2);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-861d4591{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-861d4591 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 20px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-861d4591{padding-top: 24px;padding-bottom: 24px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 20px;column-gap: 0px;order: initial;border-style: solid;border-color: var(--ast-global-color-6);background-color: var(--ast-global-color-5);;flex-wrap: wrap;}.uagb-block-2757b255.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 12px;margin-top: 16px;margin-left: 0px;margin-right: 0px;}.uagb-block-2757b255.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 16px;height: 16px;line-height: 16px;font-size: 16px;padding-left: 8px;padding-right: 8px;padding-top: 8px;padding-bottom: 8px;}.uagb-block-2757b255.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 16px;font-size: 16px;padding-left: 8px;padding-right: 8px;padding-top: 8px;padding-bottom: 8px;}.uagb-block-2757b255.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 8px;padding-right: 8px;padding-top: 8px;padding-bottom: 8px;}.uagb-block-2757b255.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 8px;padding-right: 8px;padding-top: 8px;padding-bottom: 8px;}.uagb-block-2757b255.uagb-infobox__content-wrap > svg{padding-left: 8px;padding-right: 8px;padding-top: 8px;padding-bottom: 8px;}.uagb-block-2757b255 .uagb-ifb-content > svg{padding-left: 8px;padding-right: 8px;padding-top: 8px;padding-bottom: 8px;}.uagb-block-2757b255 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;padding-left: 8px;padding-right: 8px;padding-top: 8px;padding-bottom: 8px;}.uagb-block-2757b255 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;padding-left: 8px;padding-right: 8px;padding-top: 8px;padding-bottom: 8px;}.uagb-block-2757b255.uagb-infobox__content-wrap img{padding-left: 8px;padding-right: 8px;padding-top: 8px;padding-bottom: 8px;}.uagb-block-2757b255.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-2757b255 .uagb-ifb-icon{width: 16px;line-height: 16px;}.uagb-block-2757b255 .uagb-ifb-icon > span{font-size: 16px;width: 16px;line-height: 16px;}.uagb-block-2757b255 .uagb-iconbox-icon-wrap{width: 16px;height: 16px;line-height: 16px;}.uagb-block-2757b255.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-fd943482.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-fd943482.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-941fa188 .uagb-buttons-repeater .uagb-button__icon > svg{fill: var(--ast-global-color-2);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-dd28d95c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-dd28d95c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 40px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-dd28d95c{padding-top: 64px;padding-bottom: 64px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 40px;column-gap: 0px;order: initial;background-color: var(--ast-global-color-5);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-609fec64{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-609fec64 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-609fec64{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 0px;column-gap: 0px;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-72f13e20{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-72f13e20 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-72f13e20{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 0px;column-gap: 0px;order: initial;flex-wrap: wrap;}.uagb-block-1882db2b.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-1882db2b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-1882db2b .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-1882db2b .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-1882db2b.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-1882db2b .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-1882db2b .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-1882db2b .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-1882db2b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4a8d035b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4a8d035b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-4a8d035b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 0px;column-gap: 0px;order: initial;flex-wrap: wrap;}.uagb-block-3a19b4ea.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3a19b4ea.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-3a19b4ea .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3a19b4ea .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3a19b4ea.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-3a19b4ea .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-3a19b4ea .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-3a19b4ea .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-3a19b4ea.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8f6c422d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8f6c422d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 40px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-8f6c422d{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 40px;column-gap: 0px;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0ba6d01d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0ba6d01d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-0ba6d01d{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-wrap: wrap;}.uagb-block-4e75022d.wp-block-uagb-image--layout-default figure img{border-style: none;}.uagb-block-4e75022d.wp-block-uagb-image--layout-overlay figure img{border-style: none;}.uagb-block-4e75022d.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 600px;height: auto;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-56e1cd58{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-56e1cd58 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 40px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-56e1cd58{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 40px;column-gap: 0px;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f2a241b1{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f2a241b1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 40px;}.wp-block-uagb-container.uagb-block-f2a241b1{padding-top: 10px;padding-bottom: 40px;padding-left: 10px;padding-right: 10px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 40px;order: initial;border-style: solid;border-color: var(--ast-global-color-6);flex-wrap: wrap;}.uagb-block-c5554396.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 8px;margin-top: 16px;margin-left: 0px;margin-right: 0px;}.uagb-block-c5554396.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-c5554396.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 16px;height: 16px;line-height: 16px;font-size: 16px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c5554396.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 16px;font-size: 16px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c5554396.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c5554396.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c5554396.uagb-infobox__content-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c5554396 .uagb-ifb-content > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c5554396 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c5554396 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c5554396.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-c5554396.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-c5554396 .uagb-ifb-icon{width: 16px;line-height: 16px;}.uagb-block-c5554396 .uagb-ifb-icon > span{font-size: 16px;width: 16px;line-height: 16px;}.uagb-block-c5554396 .uagb-iconbox-icon-wrap{width: 16px;height: 16px;line-height: 16px;}.uagb-block-c5554396.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-c5554396.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-c5554396.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-b685501a.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 8px;margin-top: 16px;margin-left: 0px;margin-right: 0px;}.uagb-block-b685501a.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-b685501a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 16px;height: 16px;line-height: 16px;font-size: 16px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b685501a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 16px;font-size: 16px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b685501a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b685501a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b685501a.uagb-infobox__content-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b685501a .uagb-ifb-content > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b685501a .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b685501a .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b685501a.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b685501a.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b685501a .uagb-ifb-icon{width: 16px;line-height: 16px;}.uagb-block-b685501a .uagb-ifb-icon > span{font-size: 16px;width: 16px;line-height: 16px;}.uagb-block-b685501a .uagb-iconbox-icon-wrap{width: 16px;height: 16px;line-height: 16px;}.uagb-block-b685501a.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-b685501a.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-b685501a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-737a9fe3{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-737a9fe3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 40px;}.wp-block-uagb-container.uagb-block-737a9fe3{padding-top: 0px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 40px;order: initial;flex-wrap: wrap;}.uagb-block-b31d2911.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 8px;margin-top: 16px;margin-left: 0px;margin-right: 0px;}.uagb-block-b31d2911.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-b31d2911.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 16px;height: 16px;line-height: 16px;font-size: 16px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b31d2911.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 16px;font-size: 16px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b31d2911.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b31d2911.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b31d2911.uagb-infobox__content-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b31d2911 .uagb-ifb-content > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b31d2911 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b31d2911 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b31d2911.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-b31d2911.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-b31d2911 .uagb-ifb-icon{width: 16px;line-height: 16px;}.uagb-block-b31d2911 .uagb-ifb-icon > span{font-size: 16px;width: 16px;line-height: 16px;}.uagb-block-b31d2911 .uagb-iconbox-icon-wrap{width: 16px;height: 16px;line-height: 16px;}.uagb-block-b31d2911.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-b31d2911.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-b31d2911.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-75008db2.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 8px;margin-top: 16px;margin-left: 0px;margin-right: 0px;}.uagb-block-75008db2.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-75008db2.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 16px;height: 16px;line-height: 16px;font-size: 16px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-75008db2.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 16px;font-size: 16px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-75008db2.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-75008db2.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-75008db2.uagb-infobox__content-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-75008db2 .uagb-ifb-content > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-75008db2 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-75008db2 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 16px;line-height: 16px;font-size: 16px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-75008db2.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-75008db2.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-75008db2 .uagb-ifb-icon{width: 16px;line-height: 16px;}.uagb-block-75008db2 .uagb-ifb-icon > span{font-size: 16px;width: 16px;line-height: 16px;}.uagb-block-75008db2 .uagb-iconbox-icon-wrap{width: 16px;height: 16px;line-height: 16px;}.uagb-block-75008db2.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-75008db2.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-75008db2.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0875eb55{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0875eb55 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;flex-wrap: wrap;row-gap: 48px;}.wp-block-uagb-container.uagb-block-0875eb55{padding-top: 64px;padding-bottom: 64px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 48px;order: initial;background-color: var(--ast-global-color-5);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-abcd4e61{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-abcd4e61 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-abcd4e61{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-wrap: wrap;}.uagb-block-47b7c002.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-47b7c002.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-47b7c002.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-47b7c002.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-47b7c002 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-47b7c002 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-47b7c002.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-47b7c002 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-47b7c002 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-47b7c002 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-47b7c002.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-47b7c002.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-47b7c002.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f837bf6f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f837bf6f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 48px;}.wp-block-uagb-container.uagb-block-f837bf6f{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 48px;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-27788532{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-27788532 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-27788532{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-ead7767b.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 16px;margin-top: 20px;margin-left: 0px;margin-right: 0px;}.uagb-block-ead7767b.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-ead7767b.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 14px;height: 14px;line-height: 14px;font-size: 14px;}.uagb-block-ead7767b.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 14px;font-size: 14px;}.uagb-block-ead7767b .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 14px;line-height: 14px;font-size: 14px;}.uagb-block-ead7767b .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 14px;line-height: 14px;font-size: 14px;}.uagb-block-ead7767b.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-ead7767b .uagb-ifb-icon{width: 14px;line-height: 14px;}.uagb-block-ead7767b .uagb-ifb-icon > span{font-size: 14px;width: 14px;line-height: 14px;}.uagb-block-ead7767b .uagb-iconbox-icon-wrap{width: 14px;height: 14px;line-height: 14px;}.uagb-block-ead7767b.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-ead7767b.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-ead7767b.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-200adade{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-200adade > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-200adade{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-14c90ca5.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 16px;margin-top: 20px;margin-left: 0px;margin-right: 0px;}.uagb-block-14c90ca5.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-14c90ca5.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 14px;height: 14px;line-height: 14px;font-size: 14px;}.uagb-block-14c90ca5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 14px;font-size: 14px;}.uagb-block-14c90ca5 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 14px;line-height: 14px;font-size: 14px;}.uagb-block-14c90ca5 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 14px;line-height: 14px;font-size: 14px;}.uagb-block-14c90ca5.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-14c90ca5 .uagb-ifb-icon{width: 14px;line-height: 14px;}.uagb-block-14c90ca5 .uagb-ifb-icon > span{font-size: 14px;width: 14px;line-height: 14px;}.uagb-block-14c90ca5 .uagb-iconbox-icon-wrap{width: 14px;height: 14px;line-height: 14px;}.uagb-block-14c90ca5.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-14c90ca5.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-14c90ca5.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-fd033695{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fd033695 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-fd033695{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-caa994d6.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 16px;margin-top: 20px;margin-left: 0px;margin-right: 0px;}.uagb-block-caa994d6.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-caa994d6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 14px;height: 14px;line-height: 14px;font-size: 14px;}.uagb-block-caa994d6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 14px;font-size: 14px;}.uagb-block-caa994d6 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 14px;line-height: 14px;font-size: 14px;}.uagb-block-caa994d6 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 14px;line-height: 14px;font-size: 14px;}.uagb-block-caa994d6.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-caa994d6 .uagb-ifb-icon{width: 14px;line-height: 14px;}.uagb-block-caa994d6 .uagb-ifb-icon > span{font-size: 14px;width: 14px;line-height: 14px;}.uagb-block-caa994d6 .uagb-iconbox-icon-wrap{width: 14px;height: 14px;line-height: 14px;}.uagb-block-caa994d6.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-caa994d6.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-caa994d6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e8a2a613{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e8a2a613 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 40px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-e8a2a613{padding-top: 64px;padding-bottom: 64px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 40px;column-gap: 0px;order: initial;background-color: var(--ast-global-color-5);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-51e2c002{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-51e2c002 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-51e2c002{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 0px;column-gap: 0px;order: initial;flex-wrap: wrap;}.uagb-block-fc90a4a2.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-fc90a4a2.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-fc90a4a2.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-fc90a4a2.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-fc90a4a2 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-fc90a4a2 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-fc90a4a2.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-fc90a4a2 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-fc90a4a2 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-fc90a4a2 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-fc90a4a2.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-fc90a4a2.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-fc90a4a2.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f2f686c0{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f2f686c0 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-f2f686c0{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;column-gap: 0px;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-03da51f9{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-03da51f9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;flex-wrap: wrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-03da51f9{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;column-gap: 0px;order: initial;align-items: stretch;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bca0ac81{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bca0ac81 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-bca0ac81{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;row-gap: 24px;order: initial;flex-wrap: wrap;}.uagb-block-e4fcfe5f.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 600px;height: 300px;}.uagb-block-0a7ee55f.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 600px;height: 300px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-42ebd4f6{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-42ebd4f6 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-42ebd4f6{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;row-gap: 24px;order: initial;flex-wrap: wrap;}.uagb-block-4a7f1049.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 600px;height: 300px;}.uagb-block-271d56c7.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 600px;height: 300px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3560d1a5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3560d1a5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;flex-wrap: wrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-3560d1a5{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;column-gap: 0px;order: initial;align-items: stretch;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5894fa70{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5894fa70 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-5894fa70{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;row-gap: 24px;order: initial;flex-wrap: wrap;}.uagb-block-6770cd95.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 600px;height: 300px;}.uagb-block-b201bcee.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 600px;height: 300px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0a3f9b21{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0a3f9b21 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-0a3f9b21{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;row-gap: 24px;order: initial;flex-wrap: wrap;}.uagb-block-728c8074.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 600px;height: 300px;}.uagb-block-9206fcbd.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 600px;height: 300px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7904eaf3{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7904eaf3 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: flex-start;flex-wrap: wrap;align-content: flex-start;row-gap: 48px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-7904eaf3{padding-top: 64px;padding-bottom: 64px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 48px;column-gap: 0px;order: initial;background-color: var(--ast-global-color-5);;}.wp-block-uagb-container.uagb-block-7904eaf3.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-7904eaf3.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.uagb-block-18e6815d.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-18e6815d.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-18e6815d.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-18e6815d.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-18e6815d .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-18e6815d .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-18e6815d.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-18e6815d .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-18e6815d .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-18e6815d .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-18e6815d.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-18e6815d.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-18e6815d.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-ec11566e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-ec11566e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-ec11566e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;column-gap: 0px;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-08bf843c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-08bf843c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-08bf843c{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;column-gap: 0px;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-920cad8c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-920cad8c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-920cad8c{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 0px;column-gap: 0px;order: initial;flex-wrap: wrap;}.uagb-block-5bb0bbc0.wp-block-uagb-image--layout-default figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-5bb0bbc0.wp-block-uagb-image--layout-overlay figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-5bb0bbc0.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 600px;height: 300px;}.uagb-block-5bb0bbc0.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-5bb0bbc0 .wp-block-uagb-image__figure{align-items: flex-start;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e0323075{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e0323075 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-e0323075{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 0px;column-gap: 0px;order: initial;flex-wrap: wrap;}.uagb-block-9cbc911a.wp-block-uagb-image--layout-default figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-9cbc911a.wp-block-uagb-image--layout-overlay figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-9cbc911a.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 600px;height: 300px;}.uagb-block-9cbc911a.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-9cbc911a .wp-block-uagb-image__figure{align-items: flex-start;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-01bd5354{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-01bd5354 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-01bd5354{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;column-gap: 0px;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-aa24ab14{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-aa24ab14 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-aa24ab14{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 0px;column-gap: 0px;order: initial;flex-wrap: wrap;}.uagb-block-df48cc3c.wp-block-uagb-image--layout-default figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-df48cc3c.wp-block-uagb-image--layout-overlay figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-df48cc3c.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 600px;height: 300px;}.uagb-block-df48cc3c.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-df48cc3c .wp-block-uagb-image__figure{align-items: flex-start;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c6438229{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c6438229 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-c6438229{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 0px;column-gap: 0px;order: initial;flex-wrap: wrap;}.uagb-block-34281fbc.wp-block-uagb-image--layout-default figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-34281fbc.wp-block-uagb-image--layout-overlay figure img{border-top-left-radius: 6px;border-top-right-radius: 6px;border-bottom-left-radius: 6px;border-bottom-right-radius: 6px;border-style: none;}.uagb-block-34281fbc.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 600px;height: 300px;}.uagb-block-34281fbc.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-34281fbc .wp-block-uagb-image__figure{align-items: flex-start;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a37cb94d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a37cb94d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;flex-wrap: wrap;row-gap: 40px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-a37cb94d{padding-top: 64px;padding-bottom: 64px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 40px;column-gap: 0px;order: initial;background-color: var(--ast-global-color-5);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-02b2643c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-02b2643c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 32px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-02b2643c{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 32px;column-gap: 0px;order: initial;flex-wrap: wrap;}.uagb-block-cf9e68d1 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 16px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-cf9e68d1.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-cf9e68d1.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-cf9e68d1.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-cf9e68d1.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-cf9e68d1 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-cf9e68d1 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-cf9e68d1.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-cf9e68d1 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-cf9e68d1 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-cf9e68d1 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-cf9e68d1.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-cf9e68d1.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-cf9e68d1.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0db1fe01{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0db1fe01 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 16px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-0db1fe01{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 16px;column-gap: 0px;order: initial;flex-wrap: wrap;}.uagb-block-c5887fb5.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;}.uagb-block-c5887fb5.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 20px;font-size: 20px;}.uagb-block-c5887fb5 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 20px;line-height: 20px;font-size: 20px;}.uagb-block-c5887fb5 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 20px;line-height: 20px;font-size: 20px;}.uagb-block-c5887fb5.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-c5887fb5 .uagb-ifb-icon{width: 20px;line-height: 20px;}.uagb-block-c5887fb5 .uagb-ifb-icon > span{font-size: 20px;width: 20px;line-height: 20px;}.uagb-block-c5887fb5 .uagb-iconbox-icon-wrap{width: 20px;height: 20px;line-height: 20px;}.uagb-block-c5887fb5.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-8320b8f4.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;}.uagb-block-8320b8f4.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 20px;font-size: 20px;}.uagb-block-8320b8f4 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 20px;line-height: 20px;font-size: 20px;}.uagb-block-8320b8f4 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 20px;line-height: 20px;font-size: 20px;}.uagb-block-8320b8f4.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-8320b8f4 .uagb-ifb-icon{width: 20px;line-height: 20px;}.uagb-block-8320b8f4 .uagb-ifb-icon > span{font-size: 20px;width: 20px;line-height: 20px;}.uagb-block-8320b8f4 .uagb-iconbox-icon-wrap{width: 20px;height: 20px;line-height: 20px;}.uagb-block-8320b8f4.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-26acf763.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 20px;height: 20px;line-height: 20px;font-size: 20px;}.uagb-block-26acf763.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 20px;font-size: 20px;}.uagb-block-26acf763 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 20px;line-height: 20px;font-size: 20px;}.uagb-block-26acf763 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 20px;line-height: 20px;font-size: 20px;}.uagb-block-26acf763.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-26acf763 .uagb-ifb-icon{width: 20px;line-height: 20px;}.uagb-block-26acf763 .uagb-ifb-icon > span{font-size: 20px;width: 20px;line-height: 20px;}.uagb-block-26acf763 .uagb-iconbox-icon-wrap{width: 20px;height: 20px;line-height: 20px;}.uagb-block-26acf763.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-25055c6b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-25055c6b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-25055c6b{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 0px;column-gap: 0px;order: initial;flex-wrap: wrap;}.uagb-block-2b404dfd.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 600px;height: 350px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-45f809f9{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-45f809f9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: wrap;align-content: center;row-gap: 36px;}.wp-block-uagb-container.uagb-block-45f809f9{padding-top: 64px;padding-bottom: 64px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 36px;order: initial;background-clip: padding-box;}.wp-block-uagb-container.uagb-block-45f809f9::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);}.wp-block-uagb-container.uagb-block-45f809f9.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-45f809f9.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.uagb-block-25ee98b8 .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-25ee98b8.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 24px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-25ee98b8.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-25ee98b8.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-25ee98b8.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-25ee98b8 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-25ee98b8 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-25ee98b8.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-25ee98b8 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-25ee98b8 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-25ee98b8 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-25ee98b8.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-25ee98b8.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-25ee98b8.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f9770f2e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f9770f2e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 40px;}.wp-block-uagb-container.uagb-block-f9770f2e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 40px;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a49f2642{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a49f2642 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-a49f2642{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;order: initial;flex-wrap: wrap;} .uagb-block-9d745acf.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;} .uagb-block-9d745acf .uag-star-rating__title {margin-bottom: 0;} .uagb-block-9d745acf .uag-star-rating__title{margin-right: 10px;} .uagb-block-9d745acf .uag-star-rating{font-size: 20px;}.uagb-block-5f444e21.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-5f444e21.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-5f444e21 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-5f444e21 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-5f444e21.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-5f444e21 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-5f444e21 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-5f444e21 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-5f444e21.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-7454da29.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 10px;margin-left: 0px;margin-right: 0px;}.uagb-block-7454da29.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-7454da29.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7454da29.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-7454da29 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7454da29 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-7454da29.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-7454da29 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-7454da29 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-7454da29 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-7454da29.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-7454da29.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-7454da29 .uagb-ifb-content .uagb-ifb-image-content img{width: 48px;}.uagb-block-7454da29.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 48px;}.uagb-block-7454da29 .uagb-ifb-content .uagb-ifb-left-title-image img{width: 48px;}.uagb-block-7454da29 .uagb-ifb-content .uagb-ifb-right-title-image img{width: 48px;}.uagb-block-7454da29.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-99ee0dee{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-99ee0dee > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-99ee0dee{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;order: initial;flex-wrap: wrap;} .uagb-block-ad6b7748.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;} .uagb-block-ad6b7748 .uag-star-rating__title {margin-bottom: 0;} .uagb-block-ad6b7748 .uag-star-rating__title{margin-right: 10px;} .uagb-block-ad6b7748 .uag-star-rating{font-size: 20px;}.uagb-block-73e5f556.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-73e5f556.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-73e5f556.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-73e5f556 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-73e5f556 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-73e5f556.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-73e5f556 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-73e5f556 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-73e5f556 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-73e5f556.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-73e5f556.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-73e5f556.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-833bbe7c.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 10px;margin-left: 0px;margin-right: 0px;}.uagb-block-833bbe7c.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-833bbe7c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-833bbe7c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-833bbe7c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-833bbe7c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-833bbe7c.uagb-infobox__content-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-833bbe7c .uagb-ifb-content > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-833bbe7c .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-833bbe7c .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-833bbe7c.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-833bbe7c.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-833bbe7c .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-833bbe7c .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-833bbe7c .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-833bbe7c.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-833bbe7c.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-833bbe7c .uagb-ifb-content .uagb-ifb-image-content img{width: 48px;}.uagb-block-833bbe7c.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 48px;}.uagb-block-833bbe7c .uagb-ifb-content .uagb-ifb-left-title-image img{width: 48px;}.uagb-block-833bbe7c .uagb-ifb-content .uagb-ifb-right-title-image img{width: 48px;}.uagb-block-833bbe7c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-bb3b162c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-bb3b162c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-bb3b162c{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;order: initial;flex-wrap: wrap;} .uagb-block-d648d115.wp-block-uagb-star-rating {flex-direction: row;justify-content: center;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;} .uagb-block-d648d115 .uag-star-rating__title {margin-bottom: 0;} .uagb-block-d648d115 .uag-star-rating__title{margin-right: 10px;} .uagb-block-d648d115 .uag-star-rating{font-size: 20px;}.uagb-block-3c7b265c.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-3c7b265c.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3c7b265c.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-3c7b265c .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3c7b265c .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3c7b265c.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-3c7b265c .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-3c7b265c .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-3c7b265c .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-3c7b265c.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-3c7b265c.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-3c7b265c.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-6bf5fe2a.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 0px;margin-top: 10px;margin-left: 0px;margin-right: 0px;}.uagb-block-6bf5fe2a.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-6bf5fe2a.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6bf5fe2a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6bf5fe2a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6bf5fe2a.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6bf5fe2a.uagb-infobox__content-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6bf5fe2a .uagb-ifb-content > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6bf5fe2a .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6bf5fe2a .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6bf5fe2a.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-6bf5fe2a.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-6bf5fe2a .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-6bf5fe2a .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-6bf5fe2a .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-6bf5fe2a.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-6bf5fe2a.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-6bf5fe2a .uagb-ifb-content .uagb-ifb-image-content img{width: 48px;}.uagb-block-6bf5fe2a.uagb-infobox__content-wrap .uagb-ifb-image-content img{width: 48px;}.uagb-block-6bf5fe2a .uagb-ifb-content .uagb-ifb-left-title-image img{width: 48px;}.uagb-block-6bf5fe2a .uagb-ifb-content .uagb-ifb-right-title-image img{width: 48px;}.uagb-block-6bf5fe2a.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6d512f26{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6d512f26 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-6d512f26{padding-top: 64px;padding-bottom: 64px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;column-gap: 0px;order: initial;background-clip: padding-box;}.wp-block-uagb-container.uagb-block-6d512f26::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-fdda76b5{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-fdda76b5 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-fdda76b5{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 0px;column-gap: 0px;order: initial;flex-wrap: wrap;}.uagb-block-864d55c6.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-864d55c6.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-864d55c6 .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-864d55c6 .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-864d55c6.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-864d55c6 .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-864d55c6 .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-864d55c6 .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-864d55c6.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-5b8040ed{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-5b8040ed > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-5b8040ed{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 0px;column-gap: 0px;order: initial;flex-wrap: wrap;}.uagb-block-d7d98968.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-d7d98968.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-7e0ed373.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: none;border-color: #333;}.wp-block-uagb-buttons .uagb-block-7e0ed373 .uagb-buttons-repeater.wp-block-button__link{border-style: none;border-color: #333;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media (max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media (max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}\n\";s:2:\"js\";s:854:\"document.addEventListener(\"DOMContentLoaded\", function(){ window.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-de3d4e0e' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-15570a3f' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-5658abd4' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-a3d0307e' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-4fc7d6a2' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-32051b39' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-941fa188' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-7e0ed373' );\n});\n });\";s:18:\"current_block_list\";a:13:{i:0;s:14:\"uagb\/container\";i:1;s:13:\"uagb\/info-box\";i:2;s:12:\"uagb\/buttons\";i:3;s:18:\"uagb\/buttons-child\";i:6;s:10:\"uagb\/image\";i:9;s:16:\"uagb\/star-rating\";i:10;s:11:\"core\/search\";i:11;s:10:\"core\/group\";i:12;s:12:\"core\/heading\";i:13;s:17:\"core\/latest-posts\";i:14;s:20:\"core\/latest-comments\";i:15;s:13:\"core\/archives\";i:16;s:15:\"core\/categories\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1778675975\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"],"rank_math_og_content_image":["a:2:{s:5:\"check\";s:32:\"63e5bb2606e77c891b60bd15b912f707\";s:6:\"images\";a:0:{}}"],"rank_math_internal_links_processed":["1"],"_trp_automatically_translated_slug_it_IT":["regali-religiosi"],"_trp_automatically_translated_slug_ja":["\u5b97\u6559\u7684\u30ae\u30d5\u30c8"],"_trp_automatically_translated_slug_es_ES":["regalos-religiosos"],"_trp_automatically_translated_slug_tr_TR":["dini-hediyeler"],"_trp_automatically_translated_slug_pl_PL":["prezenty-religijne"],"_trp_automatically_translated_slug_ar":["\u0627\u0644\u0647\u062f\u0627\u064a\u0627-\u0627\u0644\u062f\u064a\u0646\u064a\u0629"],"_trp_automatically_translated_slug_fr_FR":["cadeaux-religieux"],"_trp_automatically_translated_slug_de_DE":["religiose-geschenke"],"_trp_automatically_translated_slug_th":["\u0e02\u0e2d\u0e07\u0e02\u0e27\u0e31\u0e0d\u0e17\u0e32\u0e07\u0e28\u0e32\u0e2a\u0e19\u0e32"],"_trp_automatically_translated_slug_da_DK":["religiose-gaver"],"_uag_css_file_name":["uag-css-13.css"],"_uag_js_file_name":["uag-js-13.js"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"","author_link":"https:\/\/www.blumenhandlerflorist.com\/fr\/author\/"},"uagb_comment_info":0,"uagb_excerpt":null,"_links":{"self":[{"href":"https:\/\/www.blumenhandlerflorist.com\/fr\/wp-json\/wp\/v2\/pages\/13"}],"collection":[{"href":"https:\/\/www.blumenhandlerflorist.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.blumenhandlerflorist.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"replies":[{"embeddable":true,"href":"https:\/\/www.blumenhandlerflorist.com\/fr\/wp-json\/wp\/v2\/comments?post=13"}],"version-history":[{"count":0,"href":"https:\/\/www.blumenhandlerflorist.com\/fr\/wp-json\/wp\/v2\/pages\/13\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.blumenhandlerflorist.com\/fr\/wp-json\/wp\/v2\/media?parent=13"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}